{"id":82274,"date":"2018-10-01T08:04:29","date_gmt":"2018-10-01T11:04:29","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=82274"},"modified":"2018-10-01T08:04:29","modified_gmt":"2018-10-01T11:04:29","slug":"la-legislatura-mendocina-copada-por-familiares-y-amigos-de-funcionarios","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/la-legislatura-mendocina-copada-por-familiares-y-amigos-de-funcionarios\/","title":{"rendered":"La Legislatura mendocina copada por familiares y amigos de funcionarios"},"content":{"rendered":"<p>Hijos, hermanos y primos aparecen entre los beneficiados, como tambi\u00e9n allegados al poder y parientes de funcionarios.<\/p>\n<p>\u00abNo sabr\u00eda decirte cu\u00e1ntos son\u00bb. \u00abSon la misma cantidad de siempre\u00bb. Esas esquivas respuestas recibir\u00eda cualquier mortal que osara preguntar por qui\u00e9nes y cu\u00e1ntos son los asesores que hoy tiene cada diputado y senador de la Legislatura de Mendoza. Sin embargo Diario UNO logr\u00f3 acceder a la lista oficial de los asesores y secretarios de cada legislador y a la vista resaltan los ya cl\u00e1sicos nombramientos de familiares y amigos del poder.<\/p>\n<p>Y es que tal y como demostr\u00f3 el senador nacional\u00a0Julio Cobos, quien luego de la frustrada designaci\u00f3n de su novia, Natalia Ob\u00f3n, en la C\u00e1mara Federal de Apelaciones de la Justicia Federal local, volvi\u00f3 a tomarla como su asesora en el Senado, es potestad de cada legislador nombrar a quienes ser\u00e1n sus asesores y ser tambi\u00e9n \u00abel jefe\u00bb que certifique si trabaja. Para ser asesor el \u00fanico requisito es ser mayor de 18 a\u00f1os, y, claro est\u00e1, haber militado al lado del legislador o haberse ganado su afecto.<\/p>\n<p>A diferencia del Congreso de la Naci\u00f3n, que publica cu\u00e1ntos y qui\u00e9nes son los asesores de los legisladores, en Mendoza es un tema del que se habla por lo bajo, porque nadie pretende ventilarlo demasiado, aunque la Ley de Acceso a la Informaci\u00f3n P\u00fablica ya vigente se lo exigir\u00e1 el a\u00f1o que viene.<\/p>\n<p>En el Senado provincial existe la resoluci\u00f3n 433\/99, que determina que cada senador podr\u00e1 designar a dos personas: uno har\u00e1 las tareas propias de asesorarlo y el otro ser\u00e1 en los papeles su secretario administrativo, aunque tambi\u00e9n podr\u00e1 asesorarlo. Ambos llegan y se van de la Legislatura con \u00e9l cuando acaba su mandato.<\/p>\n<p>El sueldo de estas personas de confianza es un proporcional de la dieta del legislador. El asesor de un senador, que formalmente aparece en la categor\u00eda 066, percibe 45% de aquella dieta, que hoy ronda los $100.000, por lo que el ungido percibir\u00e1 alrededor de $45.000 y el secretario administrativo un porcentaje menor, aunque no se precis\u00f3 cu\u00e1nto.<\/p>\n<p>Siguiendo aquella resoluci\u00f3n, s\u00f3lo en la C\u00e1mara Alta el Estado debiera liquidar los sueldos de 76 de estos nuevos empleados, el doble de los 38 senadores, y en la C\u00e1mara Baja el n\u00famero ascender\u00eda a 96 -duplica a los 48 diputados-. Pero lo cierto es que m\u00e1s all\u00e1 del n\u00famero ideal de nombramientos, hay legisladores que suman asesores temporarios y adem\u00e1s los bloques partidarios tambi\u00e9n tienen sus propios asesores.<\/p>\n<p><strong>Beneficiar a parientes y amigos<\/strong><\/p>\n<p>A la hora de elegir a quienes los asesorar\u00e1n o quienes har\u00e1n de secretarios, Julio Cobos no es el \u00fanico que elige con el coraz\u00f3n.<\/p>\n<p>Diario UNO revis\u00f3 el listado de asesores y secretarios y a simple vista resaltaron algunos casos de nepotismo y amiguismo.<\/p>\n<p>La joven diputada Tamara Salom\u00f3n, quien asumi\u00f3 en mayo pasado, ungi\u00f3 como su asesora a su hermana Yamina Nahir Salom\u00f3n, quien adem\u00e1s aparece en sus redes sociales como vicepresidenta de la UCR de Capital.<\/p>\n<p>Una decisi\u00f3n similar tom\u00f3 en el mismo bloque el diputado Emiliano Campos, quien tiene de asesor a su primo Lucio Augusto Hisa, hijo del ex legislador Leonardo Hisa, hoy acusado del crimen de Norma Carleti.<\/p>\n<p>En la C\u00e1mara de Senadores, el malarg\u00fcino Juan Antonio Agulles tambi\u00e9n apost\u00f3 por la familia y eligi\u00f3 de secretario privado a su hijo Fabricio Agulles Mart\u00edn.<\/p>\n<p>Entre los que designaron a amigos aparece el diputado justicialista Javier Cofano, cuyo asesor es el ex legislador del mismo partido Oscar Ra\u00fal Demuru.<\/p>\n<p>En esa l\u00ednea el diputado Omar Parisi, hoy en el nuevo bloque Podemos, de corte kirchnerista, tiene de asesora seg\u00fan la informaci\u00f3n oficial a Ver\u00f3nica Valverde, ex edila de\u00a0Las Heras\u00a0y esposa del ex vicegobernador Carlos Ciurca.<\/p>\n<p>El amiguismo tambi\u00e9n se da en Senadores. La maipucina Marisa Ruggeri tiene de secretario a Juan Manuel Majul, hijo del actual subsecretario de Relaciones Institucionales de la cartera de Seguridad, N\u00e9stor Majul.<\/p>\n<p>Por su lado Adolfo Bermejo acogi\u00f3 de asesora a la ex presidenta del Concejo Deliberante de Maip\u00fa, Miriam Gallardo.<\/p>\n<p>Pero esto no es potestad s\u00f3lo de los partidos mayoritarios: tambi\u00e9n se da en el PRO. El diputado \u00c1lvaro Mart\u00ednez eligi\u00f3 como asesora a Anal\u00eda Huczak, hermana de la diputada nacional del PRO Stella Maris Huczak, y como secretario a Gabriel Alejandro Pradines, familiar del ex diputado del PD Roberto Pradines.<\/p>\n<p>El Partido Dem\u00f3crata tampoco est\u00e1 exento. El diputado Marcos Niven tiene de secretario al ex diputado de ese partido Aldo Vinci.<\/p>\n<p>Pero seguramente ese listado no es el final, porque si se rastrea m\u00e1s fino entre la militancia amiga aparecer\u00e1n otros tantos ejemplos.<\/p>\n<p><strong>Administrando el \u00abdisponible\u00bb<\/strong><\/p>\n<p>Adem\u00e1s de esos asesores estables cada senador -que como se dice puertas adentro de los bloques no tiene por qu\u00e9 saber de todos los temas en los que debe legislar- \u00abtambi\u00e9n tendr\u00e1 disponible un monto anual, que este a\u00f1o ronda los $330.000, para hacer por ejemplo\u00a0contratos\u00a0de locaciones de servicios para asesores espec\u00edficos que deber\u00e1n presentar la factura por sus servicios\u00bb, cont\u00f3 Roberto Alma, el experimentado secretario administrativo del bloque radical, quien est\u00e1 all\u00ed desde 1983, en la vuelta de la democracia. Para esto la \u00fanica condici\u00f3n es que mensualmente no puede gastar m\u00e1s de $24.000, por lo que ser\u00e1 tarea del senador distribuir los asesoramientos de manera mensual de modo de tal de no exceder esa suma o repartirla como mejor le parezca entre quienes lo iluminan en distintas \u00e1reas del saber.<\/p>\n<p>Como ese monto no es acumulable, si no lo gastan vuelve como ahorro de presupuesto, por lo cual en general se usa hasta el \u00faltimo centavo. Y es aqu\u00ed donde aparecen los grises, ya que no hay requisitos para facturar como asesor. S\u00f3lo existe la condici\u00f3n de que esa persona no debe estar en otra \u00e1rea del Estado, a excepci\u00f3n de m\u00e9dicos y docentes con una cierta cantidad de horas c\u00e1tedras.<\/p>\n<p>\u00abEl senador tiene los dos asesores que se debe, y despu\u00e9s cuenta con un contador, un abogado y tres personas m\u00e1s que trabajan en el territorio. Son las que hacen el relevamiento en el distrito que representa. Se re\u00fanen con las uniones vecinales o con las c\u00e1maras empresariales para ver qu\u00e9 es lo que necesitan\u00bb, desnud\u00f3 Roberto P\u00e1ez, quien es el secretario del senador disidente del PI, el pastor H\u00e9ctor Bonarrico, quien al separarse del frente que conform\u00f3 constituy\u00f3 un monobloque denominado MasFe y por tanto pidi\u00f3 tener para s\u00ed un prosecretario y tambi\u00e9n personal de maestranza.<\/p>\n<p>En el caso de los diputados el monto del que disponen esos legisladores es de $450.000 anuales, que seg\u00fan informaron oficialmente pueden destinar tambi\u00e9n a viajes o a hacer donaciones. Para ellos el m\u00e1ximo a gastar por mes es de $37.000 para no perjudicar el presupuesto mensual de la Legislatura.<\/p>\n<p>Este a\u00f1o, que hubo recambio de legisladores, aquellos que dejaban sus bancas y trabajaron de enero a mayo recibieron un cupo de hasta $150.000 y los que entraron, que estar\u00e1n 8 meses este a\u00f1o, dispondr\u00e1n de los $300.000 restantes.<\/p>\n<p><strong>Una tarea flexible<\/strong><\/p>\n<p>Como son designados por los legisladores, los asesores no tienen que demostrar su producci\u00f3n. Una vez que es nombrado es el legislador quien certifica mensualmente que ellos cumplieron sus tareas, presenta una nota al presidente de la c\u00e1mara, \u00e9ste la pasa al secretario administrativo y de ah\u00ed va directo a Liquidaciones.<\/p>\n<p>\u00abPor ah\u00ed hay legisladores que son del interior y tienen trabajando con ellos a gente de su departamento, que l\u00f3gicamente son quienes conocen la problem\u00e1tica y por ejemplo organizan una reuni\u00f3n con una c\u00e1mara de comercio y mandan al asesor. Entonces el que acredita el trabajo es el legislador y no tienen un horario fijo que deban cumplir o se pueda controlar\u00bb, retrat\u00f3 Sergio Pinto, secretario administrativo de la C\u00e1mara de Diputados.<\/p>\n<h6>Fuente: Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Hijos, hermanos y primos aparecen entre los beneficiados, como tambi\u00e9n allegados al poder y parientes de funcionarios.<\/p>\n","protected":false},"author":2,"featured_media":82275,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[31],"class_list":["post-82274","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/82274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=82274"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/82274\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/82275"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=82274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=82274"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=82274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}