{"id":85236,"date":"2018-12-19T07:30:00","date_gmt":"2018-12-19T10:30:00","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=85236"},"modified":"2018-12-19T07:30:00","modified_gmt":"2018-12-19T10:30:00","slug":"la-desocupacion-es-la-mas-alta-en-mendoza-desde-hace-dos-anos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/la-desocupacion-es-la-mas-alta-en-mendoza-desde-hace-dos-anos\/","title":{"rendered":"La desocupaci\u00f3n es la m\u00e1s alta en Mendoza desde hace dos a\u00f1os"},"content":{"rendered":"<p>En el tercer trimestre de 2018 creci\u00f3 a 6,4%, dos puntos m\u00e1s que en 2017. Parad\u00f3jicamente, subieron las tasas de actividad y de empleo.<\/p>\n<p>La desocupaci\u00f3n de Gran Mendoza aument\u00f3 dos puntos porcentuales en el tercer trimestre del 2018 y alcanz\u00f3 el valor m\u00e1s alto desde 2016, seg\u00fan la Encuesta Permanente de Hogares (EPH) del Instituto Nacional de Estad\u00edsticas y Censos (Indec).<\/p>\n<p>Al mismo tiempo\u00a0creci\u00f3 2,1 puntos la tasa de empleo, pero impulsada por un extraordinario aumento de la subocupaci\u00f3n.<\/p>\n<p>En detalle, el informe del organismo indica que\u00a0entre julio y septiembre de este a\u00f1o la tasa de desocupaci\u00f3n fue de 6,4%, mientras que en igual periodo del 2017 fue de 4,4%.<\/p>\n<p>Desde que Indec retom\u00f3 la medici\u00f3n, luego del periodo de \u201cemergencia estad\u00edstica\u201d, no se registra un nivel de desempleo tan alto en la provincia. Cabe aclarar que estos datos contemplan la situaci\u00f3n socioecon\u00f3mica de la poblaci\u00f3n de 14 a\u00f1os en adelante, por lo que las tasas pueden variar respecto al informe que elabora Indec con la poblaci\u00f3n de m\u00e1s de 18 a\u00f1os.<\/p>\n<p><strong>M\u00e1s gente en la b\u00fasqueda<\/strong><br \/>\nSi se analizan punto por punto los indicadores publicados por el Indec, se puede comprender mejor la realidad econ\u00f3mica de Gran Mendoza. M\u00e1s all\u00e1 del aumento de dos puntos porcentuales en la tasa de desocupaci\u00f3n, es importante destacar que\u00a0en el mismo periodo creci\u00f3 3,5 puntos la tasa de actividad (pas\u00f3 del 56,3% en el tercer trimestre del a\u00f1o pasado al 59,8% en el periodo julio-septiembre de 2018) y mejor\u00f3 2,1 puntos porcentuales la tasa de empleo (pas\u00f3 de 23,9% a 56%).<\/p>\n<p>En principio parece extra\u00f1o que crezca el empleo al mismo tiempo que aumenta la desocupaci\u00f3n, pero si se repasa la definici\u00f3n de cada \u00edtem se puede llegar a una conclusi\u00f3n l\u00f3gica de lo que ocurre en la provincia.<\/p>\n<p>La tasa de actividad muestra qu\u00e9 porcentaje de la poblaci\u00f3n se encuentra activa en el mercado laboral, esto incluye tanto a quienes tienen trabajo, como a quienes lo est\u00e1n buscando.\u00a0La tasa de empleo muestra qu\u00e9 porcentaje, dentro de la poblaci\u00f3n econ\u00f3micamente activa tiene trabajo.\u00a0En tanto,\u00a0la tasa de desempleo representa a aquellas personas que est\u00e1n buscando empleo y no lo encuentran.<\/p>\n<p>En funci\u00f3n de estos resultados, el economista Carlos Rodr\u00edguez hizo una lectura del mercado laboral de Gran Mendoza. \u201cEl aumento de la tasa de actividad indica que m\u00e1s mendocinos salieron a buscar trabajo, lo cual es l\u00f3gico en periodos de crisis, cuando el ingreso de un solo integrante de la familia no alcanza\u201d, apunt\u00f3.<\/p>\n<p>\u201cEl crecimiento del empleo demuestra que una parte de la gente que sali\u00f3 a buscar trabajo lo consigui\u00f3. Sin embargo, hay otro sector de los nuevos demandantes de trabajo que no tuvieron \u00e9xito, como lo refleja la suba de dos puntos en la tasa de desocupaci\u00f3n\u201d,\u00a0se\u00f1al\u00f3 Rodr\u00edguez.<\/p>\n<p>Se mostr\u00f3 de acuerdo la economista Leonela Navarrete, quien asegur\u00f3 que el aumento de la tasa de actividad demuestra que m\u00e1s mendocinos est\u00e1n buscan empleo. \u201cPor la ca\u00edda en el nivel de actividad econ\u00f3mica, el mercado laboral no ha alcanzado a captar a todos los nuevos demandantes de empleo. Ese es el motivo por el cual ha crecido la desocupaci\u00f3n\u201d,\u00a0explic\u00f3.<\/p>\n<p>Fue similar la postura del economista\u00a0Sebasti\u00e1n Laza, asesor del Ministerio de Econom\u00eda, Infraestructura y Energ\u00eda de Mendoza.\u00a0\u201cEs cierto que m\u00e1s gente ha salido a buscar trabajo por la ca\u00edda del poder adquisitivo de los salarios y est\u00e1 claro que muchos no lo han conseguido. Sin embargo, hay que destacar que la provincia ha seguido creando empleo, lo que ha permitido que una parte de los demandantes s\u00ed consiguieran trabajo\u201d,\u00a0destac\u00f3.<\/p>\n<p>\u201cHa sido muy positivo el esfuerzo del Gobierno de Mendoza con acciones como el Bono Fiscal y el incentivo de la econom\u00eda con la obra p\u00fablica\u201d,\u00a0agreg\u00f3 Laza.<\/p>\n<p><strong>Trabajo de menor calidad<\/strong><br \/>\nUn dato que no se puede pasar por alto en el informe de Indec es el nivel de subocupaci\u00f3n horaria,\u00a0lo que representa a quienes trabajan menos de 35 horas semanales por causas involuntarias y desean trabajar m\u00e1s.<\/p>\n<p>De acuerdo a los datos relevados por el organismo, en el tercer trimestre del a\u00f1o pasado la tasa de subocupaci\u00f3n de Gran Mendoza\u00a0era del 8,4% y actualmente es del 16,4%.<\/p>\n<p>\u201cEsa comparaci\u00f3n revela que gran parte de los mendocinos que consiguieron trabajo en el \u00faltimo a\u00f1o, obtuvieron un empleo de medio tiempo. La baja calidad de los puestos generados se asocia con la ca\u00edda del nivel de actividad econ\u00f3mica\u201d,\u00a0advirti\u00f3 Rodr\u00edguez.<\/p>\n<p>En tanto, Leonela Navarrete remarc\u00f3 que tambi\u00e9n se duplic\u00f3 la tasa de demandantes de empleo\u00a0(pas\u00f3 de 14,4% a 28,3%), valor que representa a la poblaci\u00f3n total que busca trabajo (pueden ser desocupados, subocupados e incluso ocupados). \u201cEso indica que la gente necesita trabajar m\u00e1s\u201d, concluy\u00f3 la economista.<\/p>\n<p><strong>A nivel pa\u00eds cay\u00f3 el PBI y aument\u00f3 el desempleo<\/strong><br \/>\nLa actividad econ\u00f3mica nacional cay\u00f3 3,5% en el tercer trimestre del a\u00f1o en comparaci\u00f3n con igual periodo del a\u00f1o pasado, seg\u00fan datos publicados por el Indec. Fue el segundo resultado negativo consecutivo,\u00a0luego de la retracci\u00f3n interanual del 4% registrada en el segundo trimestre.<\/p>\n<p>En lo que respecta al mercado laboral, en el periodo julio-septiembre\u00a0se registr\u00f3 una tasa de desocupaci\u00f3n del 9%, lo que representa un aumento de 0,7 puntos porcentuales respecto en relaci\u00f3n al 2017.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>En el tercer trimestre de 2018 creci\u00f3 a 6,4%, dos puntos m\u00e1s que en 2017. Parad\u00f3jicamente, subieron las tasas de actividad y de empleo.<\/p>\n","protected":false},"author":2,"featured_media":85237,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[31],"class_list":["post-85236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/85236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=85236"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/85236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/85237"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=85236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=85236"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=85236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}