{"id":85807,"date":"2019-01-11T05:34:47","date_gmt":"2019-01-11T08:34:47","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=85807"},"modified":"2019-01-11T07:38:00","modified_gmt":"2019-01-11T10:38:00","slug":"la-comuna-de-junin-tomara-su-energia-de-paneles-solares","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/la-comuna-de-junin-tomara-su-energia-de-paneles-solares\/","title":{"rendered":"La comuna de Jun\u00edn tomar\u00e1 su energ\u00eda de paneles solares"},"content":{"rendered":"<p>El municipio monta una estructura para que el sol entregue electricidad al edificio. Sostienen que aportar\u00e1 m\u00e1s del 40% de lo que consume.<\/p>\n<p>La comuna de Jun\u00edn est\u00e1 terminando por estas horas la instalaci\u00f3n de una gran malla de paneles solares que permitir\u00e1 al edificio municipal abastecerse de la energ\u00eda que consume. El proyecto, que est\u00e1 en plena ejecuci\u00f3n y ser\u00e1 puesto en marcha en d\u00edas m\u00e1s, forma parte del Programa\u00a0Jun\u00edn Punto Limpio, que naci\u00f3 en 2013 y que tiene en el reciclado de materiales y el uso de energ\u00edas limpias su principal actividad.<\/p>\n<p>La idea de que el municipio genere a trav\u00e9s de paneles solares buena parte de la energ\u00eda que consumen sus oficinas naci\u00f3 en 2018, mientras la comuna buscaba alternativas para abaratar los costos de reconvertir a led, las l\u00e1mparas de sodio del alumbrado p\u00fablico.<\/p>\n<p>\u00abLa comuna hizo contacto con la firma\u00a0Hi-Tech Factory, una empresa argentina con base en Buenos Aires y con la que acordamos montar en Jun\u00edn, una planta de reconversi\u00f3n de l\u00e1mparas de sodio a led\u00bb, explic\u00f3 el intendente Mario Abed: \u00abEs un proyecto en el que ya estamos trabajando; de esa relaci\u00f3n con la empresa surgi\u00f3 este segundo proyecto, el de montar una red de paneles solares para alimentar al edificio municipal\u00bb.<\/p>\n<p>Por estas horas, los paneles solares son ensamblados a una plataforma de cemento que se construy\u00f3 junto al edificio municipal; desde all\u00ed y a trav\u00e9s de celdas fotovoltaicas, la energ\u00eda lum\u00ednica se transformar\u00e1 en el\u00e9ctrica y ser\u00e1 conducida hacia una subestaci\u00f3n cercana.<\/p>\n<p>Maximiliano Moyano\u00a0es miembro de\u00a0Hi-Tech Factory,\u00a0la empresa que arma el sistema de celdas y esta semana, mientras supervisaba el trabajo sostuvo que, en promedio,\u00a0\u00abel municipio va a producir algo m\u00e1s del 40% de la energ\u00eda que consume a lo largo de todo el a\u00f1o\u00bb.<\/p>\n<p>Moyano se\u00f1al\u00f3 que la energ\u00eda que generar\u00e1 la red de celdas municipal se inyectar\u00e1 al sistema el\u00e9ctrico: \u00abAs\u00ed, el edificio va a seguir consumiendo la energ\u00eda del sistema general, como lo hace ahora, pero aportar\u00e1 algo m\u00e1s del 40% de ese total.<\/p>\n<p>Incluso, durante los fines de semanas o los d\u00edas feriados, el municipio entregar\u00e1 energ\u00eda al sistema el\u00e9ctrico de la ciudad pero pr\u00e1cticamente no tendr\u00e1 consumo en esas horas.<\/p>\n<p>El intendente\u00a0Abed\u00a0se mostr\u00f3 entusiasmado con el proyecto: \u00abLa comuna consume por electricidad unos 100.000 pesos y con este sistema vamos a hacer un ahorro importante pero adem\u00e1s, vamos a aportar energ\u00edas limpias\u00bb, dijo Abed y adelant\u00f3 que el sistema estar\u00e1 funcionando en los d\u00edas siguientes a la Vendimia departamental del 19 de enero.<\/p>\n<p>Pero gracias a esta primera experiencia, la idea del Ejecutivo es avanzar hacia otros campos con el uso de paneles solares y por eso, por ejemplo, estudia alternativas para llevar energ\u00eda solar a los vi\u00f1edos del departamento:\u00a0\u00abLa idea es darle la posibilidad al productor de que alimente el pozo de su finca con un panel solar, lo que reducir\u00eda mucho el gasto de corriente\u00bb, explic\u00f3\u00a0Abed\u00a0y en ese sentido dijo que ; lo que estamos estudiando son propuestas de financiamiento del sistema, para que el productor pueda instalarlo sin que el costo sea un obst\u00e1culo\u00bb.<\/p>\n<p>En cualquier caso, la red de paneles frente al municipio es el primer paso y de esa experiencia el Ejecutivo busca aprender: \u00abSomos la primera comuna que avanza en este terreno. Estamos haciendo una inversi\u00f3n de algo m\u00e1s de un mill\u00f3n de pesos pero las posibilidades que se abren son muchas\u00bb, cerr\u00f3 el intendente.<\/p>\n<p><strong>Reciclado<\/strong><br \/>\nEl Programa\u00a0Jun\u00edn Punto Limpio naci\u00f3 en 2013\u00a0y su desarrollo ha permitido que hoy, la comuna recicle hasta el 60% del pl\u00e1stico que consume el departamento. De hecho, la comuna es el primer municipio del pa\u00eds que construy\u00f3 una casa con ladrillos de pl\u00e1stico, que fueron fabricados a partir del reciclado de botellas.<\/p>\n<p>En ese contexto y junto a los galpones donde se reciclan materiales, el municipio comenz\u00f3 a levantar una planta de reconversi\u00f3n de l\u00e1mparas de sodio a led, un proyecto que tambi\u00e9n tiene el asesoramiento de\u00a0Hi-Tech Factory.<\/p>\n<p>Daniel Azcurra\u00a0est\u00e1 a cargo del Programa Jun\u00edn Punto Limpio: \u00abReemplazar una l\u00e1mpara de sodio por una de led implica, en muchos casos, tirar carcazas, cableado y transformadores. Son elementos que se descartan y que terminan formando basura electr\u00f3nica. Nuestra idea y esa ser\u00e1 la tarea de la planta que estamos montando es recuperar y reutilizar los elementos de la luminaria. En definitiva, reconvertir a led pero reciclando, que es lo que ya hacemos con el pl\u00e1stico, con la madera o el vidrio\u00bb.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El municipio monta una estructura para que el sol entregue electricidad al edificio. Sostienen que aportar\u00e1 m\u00e1s del 40% de lo que consume.<\/p>\n","protected":false},"author":2,"featured_media":85808,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-85807","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/85807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=85807"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/85807\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/85808"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=85807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=85807"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=85807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}