{"id":86438,"date":"2019-01-31T06:55:41","date_gmt":"2019-01-31T09:55:41","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=86438"},"modified":"2019-01-31T06:55:41","modified_gmt":"2019-01-31T09:55:41","slug":"empleo-en-caida-libre-al-compas-de-la-recesion","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/empleo-en-caida-libre-al-compas-de-la-recesion\/","title":{"rendered":"Empleo en ca\u00edda libre al comp\u00e1s de la recesi\u00f3n"},"content":{"rendered":"<p>Seg\u00fan datos oficiales, el sector asalariado privado concentr\u00f3 casi 118 mil de los 172 mil puestos de trabajo eliminados en un a\u00f1o. M\u00e1s de 60 mil corresponden a la industria. El comercio, 30.800, y la construcci\u00f3n resign\u00f3 18.800 empleos.<\/p>\n<p>La destrucci\u00f3n de empleo se acelera al ritmo de la recesi\u00f3n. Durante noviembre pasado, cuando la actividad econ\u00f3mica marc\u00f3 el peor registro del gobierno de Cambiemos, se contabilizaron 172.200 empleos registrados menos que el mismo mes del a\u00f1o anterior. El desplome de la demanda interna que acompa\u00f1\u00f3 al programa de ajuste fiscal y monetario agudiz\u00f3 la crisis laboral. El sector asalariado privado concentr\u00f3 las p\u00e9rdidas al marcar 117.700 puestos menos que un a\u00f1o antes. Dentro de ese universo laboral, las actividades m\u00e1s afectadas fueron las industriales. La corrida cambiaria junto con el c\u00f3ctel contractivo desplegado para intentar domarla arrasaron con 61.800 posiciones manufactureras en los \u00faltimos doce meses. El comercio registra la ca\u00edda de 30.800 empleos, la construcci\u00f3n acumul\u00f3 18.800 posiciones y el transporte experiment\u00f3 una merma de 12.400 puestos. Los datos laborales oficiales publicados ayer por la Secretar\u00eda de Trabajo evidencian la fuerte ca\u00edda en el poder adquisitivo de los asalariados hasta noviembre (ver aparte).<\/p>\n<p>La ocupaci\u00f3n industrial es uno de los sectores m\u00e1s afectados por el programa econ\u00f3mico. Registra ca\u00eddas en 35 de los 36 meses de la gesti\u00f3n de Cambiemos cubiertos por las estad\u00edsticas oficiales. En noviembre pasado, alcanzaron a 125.000 los puestos de trabajo destruidos desde que comenz\u00f3 el gobierno de Mauricio Macri. La destrucci\u00f3n acumulada en tres a\u00f1os equivale al 10 por ciento de las posiciones manufactureras que exist\u00edan al finalizar 2015. El derrape industrial se aceler\u00f3 durante la segunda mitad del a\u00f1o pasado. En noviembre, la actividad econ\u00f3mica registr\u00f3 una ca\u00edda del 7,5 por ciento frente al mismo mes de 2017. Uno de los principales factores para explicar ese desempe\u00f1o fue el desplome industrial que marc\u00f3 un retroceso de 12,6 por ciento. El impacto laboral fue directo. En noviembre se contabilizaron 9600 empleos menos que en octubre. La medici\u00f3n sin estacionalidad, por su parte, marc\u00f3 la p\u00e9rdida de 10.900 empleos.<\/p>\n<p>Con las cifras publicadas ayer por la Secretar\u00eda de Trabajo, la industria manufacturera alcanz\u00f3 el nivel de empleo m\u00e1s bajo en una d\u00e9cada. Fue precisamente en 2009 cuando la crisis internacional comenz\u00f3 a golpear sobre el mercado de trabajo argentino. Entonces, uno de los principales instrumentos utilizados por el gobierno para frenar despidos colectivos y suspensiones fue el Programa de Recuperaci\u00f3n Productiva. El Repro es un subsidio a las empresas a trav\u00e9s del cual el Estado se hace cargo del pago de una parte del salario a los trabajadores del sector privado durante un per\u00edodo para intentar atravesar la crisis. Las empresas que hoy solicitan el instrumento chocan con la negativa del Ministerio de Producci\u00f3n y Trabajo.<\/p>\n<p>Comprometida con el programa de ajuste y reformas acordado con el FMI, la cartera encabezada por Dante Sica tampoco se muestra receptiva a los pedidos empresarios por beneficios impositivos o medidas de protecci\u00f3n comercial. La \u00fanica alternativa en el men\u00fa oficial es la flexibilizaci\u00f3n laboral. Como revel\u00f3 este diario la semana pasada, el primer intento del a\u00f1o tuvo lugar en la industria textil. El secretario de Trabajo, Lucas Aparicio, aprovech\u00f3 los despidos masivos y el cierre de f\u00e1bricas para proponer la incorporaci\u00f3n de una serie de instrumentos previstos en la fallida reforma laboral de hace dos a\u00f1os. A pesar de los esfuerzos oficiales, la iniciativa recibi\u00f3 un in\u00e9dito rechazo bilateral desde los sindicatos y las c\u00e1maras empresarias.<\/p>\n<p>Pero la crisis laboral excede a la actividad industrial. En noviembre 11 de los 14 sectores relevados marcaron una contracci\u00f3n en la medici\u00f3n mensual sin estacionalidad. De la mano de la ca\u00edda de la demanda interna, el comercio experiment\u00f3 la destrucci\u00f3n de 9800 empleos frente a octubre mientras que las actividades empresariales registraron la p\u00e9rdida de 4500 posiciones. La construcci\u00f3n, por su parte, contin\u00faa mostrando el impacto de la incertidumbre financiera sobre los proyectos privados y el ajuste de la obra p\u00fablica. Fueron 4300 las posiciones destruidas en noviembre. La Encuesta de Indicadores Laborales anticipa la persistencia de la crisis del empleo en diciembre, que conservar\u00e1 a la actividad industrial y el comercio como principales afectados.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan datos oficiales, el sector asalariado privado concentr\u00f3 casi 118 mil de los 172 mil puestos de trabajo eliminados en un a\u00f1o. M\u00e1s de 60 mil corresponden a la industria. El comercio, 30.800, y la construcci\u00f3n resign\u00f3 18.800 empleos.<\/p>\n","protected":false},"author":2,"featured_media":86439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[21],"class_list":["post-86438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-nacional","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/86438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=86438"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/86438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/86439"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=86438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=86438"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=86438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}