{"id":86477,"date":"2019-01-31T07:58:41","date_gmt":"2019-01-31T10:58:41","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=86477"},"modified":"2019-01-31T07:58:41","modified_gmt":"2019-01-31T10:58:41","slug":"macri-pudo-con-vidal-y-larreta-pero-no-con-cornejo-y-morales","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/macri-pudo-con-vidal-y-larreta-pero-no-con-cornejo-y-morales\/","title":{"rendered":"Macri pudo con Vidal y Larreta, pero no con Cornejo y Morales"},"content":{"rendered":"<p>El Presidente quiere que Mendoza y Jujuy tampoco desdoblen. En Buenos Aires ya hubo acuerdo.<\/p>\n<p>Cambiemos gobierna cinco de los 24 distritos del pa\u00eds: la ciudad y la provincia de Buenos Aires, con el PRO, y Corrientes, Mendoza y Jujuy, en manos de los radicales, que para la Casa Rosada son naturalmente los d\u00edscolos y los m\u00e1s dif\u00edciles de persuadir.<\/p>\n<p>Corrientes no elige gobernador este a\u00f1o. Por eso, con el anuncio de Mar\u00eda Eugenia Vidal de no anticipar las elecciones bonaerenses y hacerlas el mismo d\u00eda que las nacionales, decisi\u00f3n que tambi\u00e9n tom\u00f3 ayer el porte\u00f1o Horacio Rodr\u00edguez Larreta, el Gobierno ahora intenta convencer a Alfredo Cornejo y a Gerardo Morales \u2013ambos de la UCR\u2013 de que las unifiquen. Pero por ahora no hay respuesta.<\/p>\n<p>En la Casa Rosada entienden que despegarse de la elecci\u00f3n nacional en los distritos gobernados por el oficialismo es una se\u00f1al de debilidad de Macri en su af\u00e1n de ser reelegido.<\/p>\n<p>Adem\u00e1s, conf\u00edan en que una relativa estabilizaci\u00f3n de la econom\u00eda en los pr\u00f3ximos meses ofrezca una mejora en la intenci\u00f3n de voto del l\u00edder del PRO, aprovechando la polarizaci\u00f3n con Cristina Kirchner y su pesada imagen negativa.<\/p>\n<p>Con estos argumentos, esta semana la Rosada logr\u00f3 torcerle el brazo a Vidal y, al parecer, tambi\u00e9n a Larreta. Pero no a Cornejo y a Morales.<\/p>\n<p>Tanto el mendocino como el juje\u00f1o no quieren ir en la misma boleta de Macri porque entienden que la deca\u00edda imagen del Presidente en las encuestas podr\u00eda estropear el desempe\u00f1o de los candidatos locales.<\/p>\n<p>Morales directamente no quiere saber nada con unificar: fuentes del Gobierno juje\u00f1o dijeron a\u00a0La Voz\u00a0que para el mandatario provincial, que buscar\u00e1 su reelecci\u00f3n, no tiene ning\u00fan sentido hacer coincidir las elecciones el domingo 27 de octubre porque la provincia norte\u00f1a representa tan s\u00f3lo el 1% del padr\u00f3n nacional, de modo que no tendr\u00eda gravitaci\u00f3n alguna en la\u00a0performance\u00a0electoral de Macri, pero s\u00ed podr\u00eda significar un da\u00f1o importante para los postulantes locales.<\/p>\n<p>\u201cLa mayor\u00eda de las elecciones anticipadas ser\u00e1n derrotas para Macri. Nosotros podemos llevarle un triunfo en medio de tantas malas noticias. Que el Presidente venga a levantarle la mano a un candidato de Cambiemos ser\u00eda un avent\u00f3n para la presidencial\u201d, dijo un colaborador de Morales.<\/p>\n<p>Algunos estudios de opini\u00f3n en Jujuy arrojan resultados lapidarios para la Casa Rosada: Macri aparece midiendo 12 puntos, contra n\u00fameros que permiten avizorar una c\u00f3moda reelecci\u00f3n del gobernador radical.<\/p>\n<p>Mendoza<\/p>\n<p>En Mendoza, a su vez, Cornejo es considerado un buen administrador, pero a diferencia de Morales, el cuyano no puede ser reelegido. Esta vez, competir\u00e1 por una banca de diputado nacional.<\/p>\n<p>Sin embargo, es el hombre fuerte de la tierra del sol y del buen vino, y tambi\u00e9n se reh\u00fasa a unificar las elecciones.<\/p>\n<p>En Mendoza, seg\u00fan algunas encuestas, Cornejo tiene un 60 por ciento de imagen positiva contra un 40 por ciento de la de Macri; pero la diferencia sustancial entre ambos radica en la imagen negativa: la del gobernador es muy baja y la del Presidente est\u00e1 por las nubes. A diferencia de Jujuy, donde la fecha de las elecciones provinciales la define el gobernador con un decreto, en Mendoza la ley establece que deben ser antes de las nacionales (las primarias, en junio, y las generales, en septiembre), aunque le otorga la facultad al Poder Ejecutivo de unificarlas con la nacional.<\/p>\n<p>Cornejo est\u00e1 en una encrucijada: se enfrenta a la presi\u00f3n nacional de unificar y al reclamo de los intendentes, que quieren que los comicios provinciales sean anticipados, para no quedar pegados a Macri.<\/p>\n<p>Tucum\u00e1n<\/p>\n<p>El gobernador quiere a Cristina dentro del PJ.<\/p>\n<p>El gobernador de Tucum\u00e1n, Juan Manzur, insisti\u00f3 en \u201cla necesidad de lograr la unidad\u201d del PJ \u201cpara darles respuestas a los argentinos\u201d y consider\u00f3 que ese paso debe concretarse con la expresidenta Cristina Fern\u00e1ndez de Kirchner \u201cdentro\u201d del espacio pol\u00edtico. El mandatario reiter\u00f3 su convocatoria a la unidad nacional del partido.<\/p>\n<h6>Fuente: La Voz<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El Presidente quiere que Mendoza y Jujuy tampoco desdoblen. En Buenos Aires ya hubo acuerdo.<\/p>\n","protected":false},"author":2,"featured_media":86478,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[21],"class_list":["post-86477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-argentina"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/86477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=86477"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/86477\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/86478"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=86477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=86477"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=86477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}