{"id":87540,"date":"2019-02-28T05:37:34","date_gmt":"2019-02-28T08:37:34","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=87540"},"modified":"2019-02-28T07:40:27","modified_gmt":"2019-02-28T10:40:27","slug":"se-quebro-cambia-mendoza-el-pd-va-a-4-municipales-con-candidatos-propios","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/se-quebro-cambia-mendoza-el-pd-va-a-4-municipales-con-candidatos-propios\/","title":{"rendered":"Se quebr\u00f3 Cambia Mendoza: el PD va a 4 municipales con candidatos propios"},"content":{"rendered":"<p>Este martes 25 era la fecha l\u00edmite para presentar los frentes partidarios que competir\u00e1n en las cuatro comunas que decidieron adelantar sus comicios: San Mart\u00edn, San Rafael, Tunuy\u00e1n y Lavalle. Rotas las negociaciones con el radicalismo, y seg\u00fan adjudican los gansos por presiones del gobernador Alfredo Cornejo, en esas comunas el Partido Dem\u00f3crata no ir\u00e1 dentro de Cambia Mendoza y s\u00ed llevar\u00e1 sus propios alfiles para buscar las intendencias. Adem\u00e1s es \u00abmuy probable\u00bb que no haya retorno al Frente y el PD vaya por fuera tambi\u00e9n en las elecciones provinciales.<\/p>\n<p>\u00abNosotros ven\u00edamos hablando muy bien con Rodolfo Suarez la posibilidad de arreglar lo que suced\u00eda en San Rafael y San Mart\u00edn, en donde dos candidatos nuestros quer\u00edan ir solos, porque en las otros dos comunas (Lavalle y Tunuy\u00e1n) \u00edbamos en el frente. Pero se endureci\u00f3 la posici\u00f3n un d\u00eda antes, Cornejo toma el comando de las acciones y presenta el frente para los 4 departamentos y la provincia en un solo paquete en donde no hab\u00eda posibilidad de disidencia. Se estaba adentro o afuera. As\u00ed es que nos quedamos afuera del frente en esas comunales\u00bb, explic\u00f3 el diputado provincial y presidente del PD, Marcos Niven.<\/p>\n<p>El legislador precis\u00f3 que la decisi\u00f3n tambi\u00e9n obedeci\u00f3 a que los dos candidatos que pretend\u00edan competir por fuera del frente en San Rafael y San Mart\u00edn, \u00abcontaban con la autorizaci\u00f3n de la Junta Central de Gobierno para hacerlo, de hecho les hab\u00eda dado libertad de acci\u00f3n para presentarse. Ahora no pod\u00edamos decirle a esos candidatos, que hace m\u00e1s de un mes est\u00e1n trabajando y militando, que no se pod\u00edan presentar\u00bb, dijo aunque admiti\u00f3 que la relaci\u00f3n dentro de Cambia Mendoza se ha ido deteriorando al punto de que \u00abes muy probable que el PD juegue por fuera en las pr\u00f3ximas elecciones y no haya retorno\u00bb.<\/p>\n<p>Los candidatos a los que alude Niven son el escribano Pablo Fracaro (49) que va a competir por San Rafel, y en San Mart\u00edn ir\u00e1 el ingeniero Armando Magistretti (52). En tanto, resta definir quienes ser\u00e1n las apuestas para Tunuy\u00e1n y Lavalle.<\/p>\n<p>\u00bfUna forma de debilitar a De Marchi?<br \/>\nA la hora de tratar de entender la motivaci\u00f3n del radicalismo para presentar as\u00ed las listas del Frente Cambia Mendoza, Niven se permiti\u00f3 una lectura netamente electoral.<\/p>\n<p>\u00abEl hecho de que Omar De Marchi haya insistido en enfrentar al candidato a gobernador del radicalismo en una interna\u00a0 lo molest\u00f3 a Cornejo, porque indudablemente un socio que pod\u00eda tener De Marchi en el frente era el PD, ahora con el PD afuera lo debilita a De Marchi en su intento de competir por dentro de Cambia Mendoza. Eso pudo haber influenciado\u00bb, especul\u00f3.<\/p>\n<p>Niven podr\u00eda ser otra vez candidato a gobernador<br \/>\nEste nuevo esquema pol\u00edtico obliga a los gansos a definir en el corto plazo quien podr\u00eda ser su candidato a gobernador, si es que confirman que abandonan Cambia Mendoza. Si bien a\u00fan es pronto para ponerle nombre a esa inc\u00f3gnita, es muy posible que el hoy diputado provincial y presidente del PD pueda ser la cara de esa tercera opci\u00f3n que tendr\u00e1n los electores mendocinos.<\/p>\n<h6>Fuente: Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Este martes 25 era la fecha l\u00edmite para presentar los frentes partidarios que competir\u00e1n en las cuatro comunas que decidieron adelantar sus comicios: San Mart\u00edn, San Rafael, Tunuy\u00e1n y Lavalle. <\/p>\n","protected":false},"author":2,"featured_media":87541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[31],"class_list":["post-87540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/87540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=87540"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/87540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/87541"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=87540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=87540"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=87540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}