{"id":87600,"date":"2019-03-01T06:55:41","date_gmt":"2019-03-01T09:55:41","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=87600"},"modified":"2019-03-01T07:24:31","modified_gmt":"2019-03-01T10:24:31","slug":"una-cifra-alarmante-en-tres-anos-cerraron-2-600-kioscos-en-mendoza","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/una-cifra-alarmante-en-tres-anos-cerraron-2-600-kioscos-en-mendoza\/","title":{"rendered":"Una cifra alarmante: en tres a\u00f1os cerraron 2.600 kioscos en Mendoza"},"content":{"rendered":"<p>La cifra es alarmante: en los \u00faltimos tres a\u00f1os se cerraron 2.600 kioscos en Mendoza. En Argentina en el mismo lapso de tiempo bajaron la persiana unos 28.000 negocios de ese rubro. As\u00ed lo confirm\u00f3 el presidente de la UKRA, N\u00e9stor Adri\u00e1n Palacios.<\/p>\n<p>El titular de la Uni\u00f3n de Kiosqueros de la Rep\u00fablica Argentina fue consultado acerca de la realidad mendocina. \u00abEn el 2015 hab\u00eda 6.800 registrados en Mendoza y se perdieron 2.600\u00bb, confirm\u00f3.<\/p>\n<p>Palacios se\u00f1al\u00f3 en\u00a0Radio Nihuil\u00a0que \u00ablamentablemente esa cifra da un alerta. La situaci\u00f3n econ\u00f3mica del pa\u00eds no se ha reactivado en materia de consumo\u00bb.<\/p>\n<p>\u00abLo hemos chequeado con nuestros proveedores, Arcor y Coca Cola y las dos tabacaleras importantes de nuestro pa\u00eds. El n\u00famero es lamentable\u00bb, expres\u00f3.<\/p>\n<p>\u00abArcor el a\u00f1o pasado lanz\u00f3 un comunicado de prensa dando a conocer que estaba en una situaci\u00f3n de crisis porque los kioscos del pa\u00eds estaban comprando menos productos y apuntaban a segundas y terceras marcas. Coca Cola tambi\u00e9n est\u00e1 en crisis\u00bb, grafic\u00f3.<\/p>\n<h6>Fuente: Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La cifra es alarmante: en los \u00faltimos tres a\u00f1os se cerraron 2.600 kioscos en Mendoza. En Argentina en el mismo lapso de tiempo bajaron la persiana unos 28.000 negocios de ese rubro<\/p>\n","protected":false},"author":2,"featured_media":87601,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[31],"class_list":["post-87600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/87600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=87600"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/87600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/87601"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=87600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=87600"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=87600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}