{"id":87749,"date":"2019-03-11T07:47:00","date_gmt":"2019-03-11T10:47:00","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=87749"},"modified":"2019-03-11T07:47:00","modified_gmt":"2019-03-11T10:47:00","slug":"las-heras-quiere-metrobus-capital-y-lujan-de-cuyo-no","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/las-heras-quiere-metrobus-capital-y-lujan-de-cuyo-no\/","title":{"rendered":"Las Heras quiere Metrobus, Capital y Luj\u00e1n de Cuyo, no"},"content":{"rendered":"<p>Daniel Orozco, intendente lasherino, manifest\u00f3 que est\u00e1n haciendo los trabajos primarios para hacerlo en un futuro en Av. San Mart\u00edn.<\/p>\n<p>El sistema troncal que ya se estren\u00f3 en\u00a0Godoy Cruz y Guaymall\u00e9n, m\u00e1s conocido como\u00a0Metrobus, seguir\u00e1 en una segunda etapa en el departamento conducido por Tadeo Garc\u00eda Zalazar. Sin embargo,\u00a0Capital y Luj\u00e1n lo descartaron por el momento, y Las Heras se incluir\u00e1 en los pr\u00f3ximos meses, seg\u00fan detallaron a\u00a0Los Andes.<\/p>\n<p>En conjunto con la\u00a0aplicaci\u00f3n del Mendotran, la secretar\u00eda de Servicios P\u00fablicos\u00a0realiz\u00f3 un relevamiento de las avenidas m\u00e1s importantes de los departamentos del Gran Mendoza, con la posibilidad a mediano plazo de mejorar la circulaci\u00f3n en las mismas con un tr\u00e1nsito m\u00e1s fluido de los veh\u00edculos, pero sobre todo del transporte p\u00fablico, a trav\u00e9s de la creaci\u00f3n de los\u00a0recorridos \u00a0troncales.<\/p>\n<p>Sin embargo, son los municipios los que tienen la potestad de ejecutarlo, y por el momento,\u00a0Rodolfo Su\u00e1rez, jefe comunal de Capital; y Omar De Marchi, de Luj\u00e1n de Cuyo, negaron que se vaya a establecer un troncal similar al que ya se aplic\u00f3 en Godoy Cruz y Guaymall\u00e9n. En tanto, Daniel Orozco, de Las Heras, manifest\u00f3 que est\u00e1n haciendo los trabajos primarios para hacerlo en un futuro en av. San Mart\u00edn.<\/p>\n<p>Por el lado de Luj\u00e1n, el Intendente sostuvo a\u00a0Los Andes\u00a0que si bien en alg\u00fan momento se hizo referencia a poder realizarlo, declar\u00f3 que \u201cno hab\u00eda chances f\u00edsicas\u201d con relaci\u00f3n a las avenidas y que qued\u00f3 descartado ya que no iba a poder tener\u00a0conexi\u00f3n con otro departamento, como Godoy Cruz.<\/p>\n<p>En tanto, Su\u00e1rez justific\u00f3 que\u00a0\u201cel Microcentro es un lugar tur\u00edstico\u00a0y no es amigable que pase el Metrobus por all\u00ed, ya que se realizan muchos eventos art\u00edsticos durante el a\u00f1o\u201d, como por ejemplo la\u00a0V\u00eda Blanca o el Carrusel en Vendimia.<\/p>\n<p>Quien dijo que s\u00ed est\u00e1n\u00a0avanzando en la instalaci\u00f3n de un troncal es Orozco, que destac\u00f3 que se est\u00e1 realizando la planificaci\u00f3n para una futura red troncal en la avenida San Mart\u00edn. Pero aclar\u00f3 que \u201cser\u00eda en una pr\u00f3xima gesti\u00f3n\u201d, por lo que la decisi\u00f3n final la tomar\u00eda quien gane la intendencia en estas elecciones.<\/p>\n<p>L\u00eda Mart\u00ednez, directora de Planificaci\u00f3n de Transporte de la Secretar\u00eda de Servicios P\u00fablicos, explic\u00f3\u00a0que en el estudio que se hizo se tom\u00f3 en cuenta las avenidas que concentraban el mayor caudal del transporte p\u00fablico, y de ah\u00ed la posibilidad de mejorar el flujo de tr\u00e1nsito.<\/p>\n<p>\u201cLo que nosotros hemos hecho es un trabajo de hacer llegar a los equipos t\u00e9cnicos propuestas para mejorar la infraestructura, y establecer decisiones estrat\u00e9gicas\u201d, asegur\u00f3 la funcionaria.<\/p>\n<p>Como avenidas potenciales a la instalaci\u00f3n de una red troncal a futuro, la funcionaria nombr\u00f3 a la\u00a0calle Las Heras y su continuaci\u00f3n en Juan B. Justo en Ciudad,\u00a0que conecta el departamento con la\u00a0Universidad Nacional de Cuyo; y otros ingresos desde Guaymall\u00e9n a la Ciudad, adem\u00e1s de la calle Godoy Cruz, donde ya est\u00e1 el troncal, a la Adolfo Calle y la Bandera de Los Andes.<\/p>\n<p><strong>Segunda etapa<\/strong><br \/>\nMientras tanto, en Godoy Cruz se avanza a paso firme. La semana pasada se inaugur\u00f3 la primera etapa del troncal en la\u00a0Avenida San Mart\u00edn, desde\u00a0Yrigoyen hasta la calle Tiburcio Benegas, que es la que concentra el\u00a070% del transporte p\u00fablico\u00a0de toda la obra, ya que la mayor\u00eda de los micros se desv\u00eda hacia el\u00a0Puente Olive.<\/p>\n<p>El resto se realizar\u00e1 desde\u00a0Tiburcio Benegas hasta la calle Granaderos,\u00a0donde se ubica rotonda del puente de la ciclov\u00eda. Diego Coronel, secretario de Obras y Servicios P\u00fablicos del departamento, detall\u00f3 que a partir del\u00a015 de marzo arrancar\u00e1n los trabajos,\u00a0y se espera que finalice a mediados o fines de abril. En total, todo el troncal de la\u00a0calle San Mart\u00edn desde Yrigoyen hasta Granaderos, tendr\u00e1 un valor de 72,69 millones de pesos.<\/p>\n<p>Sin embargo, tambi\u00e9n se est\u00e1n llevando a cabo estudios en la\u00a0Panamericana,\u00a0desde la rotonda de la\u00a0Ciclov\u00eda hasta la Avenida del Trabajo, en el Parque Benegas. \u201cLa geometr\u00eda de la calle es distinta a la que ya est\u00e1 hecha el troncal, estamos en etapa de formulaci\u00f3n en el lugar\u201d,\u00a0finaliz\u00f3 Coronel.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Daniel Orozco, intendente lasherino, manifest\u00f3 que est\u00e1n haciendo los trabajos primarios para hacerlo en un futuro en Av. San Mart\u00edn. \u00a0<\/p>\n","protected":false},"author":2,"featured_media":87750,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31],"class_list":["post-87749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-municipal","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/87749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=87749"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/87749\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/87750"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=87749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=87749"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=87749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}