{"id":88189,"date":"2019-03-21T05:17:38","date_gmt":"2019-03-21T08:17:38","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=88189"},"modified":"2019-03-21T07:20:21","modified_gmt":"2019-03-21T10:20:21","slug":"el-gobernador-de-mendoza-acepto-que-los-cuatro-intendentes-del-pj-vayan-por-un-nuevo-mandato","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/el-gobernador-de-mendoza-acepto-que-los-cuatro-intendentes-del-pj-vayan-por-un-nuevo-mandato\/","title":{"rendered":"El gobernador de Mendoza acept\u00f3 que los cuatro intendentes del PJ vayan por un nuevo mandato"},"content":{"rendered":"<p>El gobernador Alfredo Cornejo anunci\u00f3 este mi\u00e9rcoles que los cuatro intendentes del Partido Justicialista que recurrieron a la Justicia \u00abse postulen en las pr\u00f3ximas elecciones, pero con la condici\u00f3n de que \u00e9stos no pongan obst\u00e1culos para que la Corte resuelva la cuesti\u00f3n de fondo sobre las reelecciones\u201d.<\/p>\n<p>En conferencia de prensa, el titular del Ejecutivo dijo con cierto tono de enojo: \u201cHe instruido al asesor y al ministro de Gobierno para que no ejerzan ninguna actividad procesal m\u00e1s\u201d.<\/p>\n<p>Esto se da luego del fracaso de la audiencia que hubo en la ma\u00f1ana de este mi\u00e9rcoles en la Suprema Corte de Justicia, donde estuvieron los cuatro intendentes implicados: Roberto Righi (Lavalle), Jorge Gim\u00e9nez (San Mart\u00edn), Mart\u00edn Aveiro (Tunuy\u00e1n) y Emir F\u00e9liz (San Rafael).<\/p>\n<p>Cornejo acus\u00f3 de \u201csabotaje institucional\u201d el accionar de estos jefes comunales. \u201cA ra\u00edz de la actitud asumida por los cuatro intendentes justicialistas, estamos ante un nuevo sabotaje institucional, dilatando a\u00fan m\u00e1s los plazos para poder presentarse a las elecciones que ellos mismos han adelantado para el 28 de abril\u201d, enfatiz\u00f3.<\/p>\n<p>\u201cNo ser\u00e9 obst\u00e1culo para que los cuatro intendentes participen en este proceso electoral. Es el \u00fanico inter\u00e9s de estas cuatro personas, que han invocado sus derechos y no los de los ciudadanos, agreg\u00f3 el gobernador en su discurso.<\/p>\n<p>En cuanto al tema judicial, Cornejo dijo que le solicitar\u00e1 a la Corte Suprema de Justicia \u201cla pronta resoluci\u00f3n del conflicto de fondo, declarando constitucional las re reelecciones indefinidas para un futuro inmediato. No solo lo pido como Gobernador, sino porque la inmensa mayor\u00eda de la poblaci\u00f3n se ha manifestado contra que se limiten las reelecciones de los intendentes a solo dos per\u00edodos\u201d.<\/p>\n<p>\u201cLos cuatro intendentes justicialistas han ido a la Corte no quieren que sea constitucional el decreto. No son v\u00edctimas, tres de ellos hace 16 a\u00f1os que gobiernan sus municipios\u201d, manifest\u00f3 el gobernador, visiblemente molesto por la situaci\u00f3n.<\/p>\n<h6>Fuente: Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador Alfredo Cornejo anunci\u00f3 este mi\u00e9rcoles que los cuatro intendentes del Partido Justicialista que recurrieron a la Justicia \u00abse postulen en las pr\u00f3ximas elecciones, pero con la condici\u00f3n de que \u00e9stos no pongan obst\u00e1culos para que la Corte resuelva la cuesti\u00f3n de fondo sobre las reelecciones\u201d.<\/p>\n","protected":false},"author":2,"featured_media":88190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[31],"class_list":["post-88189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/88189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=88189"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/88189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/88190"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=88189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=88189"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=88189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}