{"id":88522,"date":"2019-03-28T05:43:24","date_gmt":"2019-03-28T08:43:24","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=88522"},"modified":"2019-03-28T07:46:22","modified_gmt":"2019-03-28T10:46:22","slug":"finalmente-se-constituyo-en-mendoza-la-paritaria-provincial-para-los-empleados-municipales","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/finalmente-se-constituyo-en-mendoza-la-paritaria-provincial-para-los-empleados-municipales\/","title":{"rendered":"Finalmente se constituy\u00f3 en Mendoza la paritaria provincial para los empleados municipales"},"content":{"rendered":"<p>Luego de algunas idas y venidas, la paritaria provincial se abri\u00f3 a la discusi\u00f3n con los trabajadores municipales. En ese sentido, desde la Federaci\u00f3n de sindicatos de la provincia de Mendoza, de la cual es parte el sindicato de empleados municipales hab\u00eda planteado el aumento del 40% y la cl\u00e1usula gatillo.<\/p>\n<p>Para la Federac\u00ed\u00f3n, el tema de dicha cl\u00e1usula es fundamental en funci\u00f3n de la inflaci\u00f3n que d\u00eda a d\u00eda parece tener un rumbo incierto.<\/p>\n<p>Sin embargo, la reuni\u00f3n debi\u00f3 pasar a un cuarto intermedio hasta el d\u00eda\u00a0Jueves 28\u00a0de marzo debido a que representantes de ATE, encabezados por\u00a0Roberto Macho\u00a0produjeron agresiones tratando de entras a la reuni\u00f3n paritaria, sabiendo que por ley no pueden participar de las paritarias municipales, seg\u00fan indicaron desde la propia Federaci\u00f3n a este medio.<\/p>\n<p>Desde la Federaci\u00f3n sostuvieron, que la intenci\u00f3n es sentarse a la mesa el Jueves y poder acordar un monto para empezar, y la cl\u00e1usula gatillo que permitir\u00e1 estar a resguardo de la inflaci\u00f3n venidera.<\/p>\n<p>Fuente:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luego de algunas idas y venidas, la paritaria provincial se abri\u00f3 a la discusi\u00f3n con los trabajadores municipales.<\/p>\n","protected":false},"author":2,"featured_media":88523,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[31],"class_list":["post-88522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/88522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=88522"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/88522\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/88523"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=88522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=88522"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=88522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}