{"id":89684,"date":"2019-05-01T17:38:18","date_gmt":"2019-05-01T20:38:18","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=89684"},"modified":"2019-05-01T20:40:28","modified_gmt":"2019-05-01T23:40:28","slug":"el-pj-mendocino-triunfo-en-las-primarias-adelantadas-en-cuatro-comunas","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/el-pj-mendocino-triunfo-en-las-primarias-adelantadas-en-cuatro-comunas\/","title":{"rendered":"El PJ mendocino triunf\u00f3 en las primarias adelantadas en cuatro comunas"},"content":{"rendered":"<p>Ayer hubo PASO en San Mart\u00edn, Lavalle, Tunuy\u00e1n y San Rafael. El mejor resultado del frente Eleg\u00ed se dio en el departamento del Valle de Uco.<\/p>\n<p>Termin\u00f3 el primer round electoral de 2019 en Mendoza. Esta vez fueron las primarias abiertas, simult\u00e1neas y obligatorias (PASO) para elegir intendentes y concejales en los departamentos de San Mart\u00edn, Lavalle, Tunuy\u00e1n y San Rafael. En estas cuatro comunas gobernadas desde hace a\u00f1os por el PJ, los resultados confirmaron esa tendencia.<\/p>\n<p>\u00bfEs una derrota de Alfredo Cornejo?\u00a0El peronismo sin dudas lo anuncia como una primera derrota que el peronismo explica a la crisis econ\u00f3mica y a la cercan\u00eda de Cornejo al Gobierno de Mauricio Macri.<\/p>\n<p>En Tunuy\u00e1n,\u00a0el intendente\u00a0Mart\u00edn Aveiro arras\u00f3 con el 70% de los votos; tal vez por eso el precandidato as la gobernaci\u00f3n del Frente Eleg\u00ed Alejandro Bermejo viaj\u00f3 a ese departamento para acompa\u00f1ar a Aveiro, el gran ganador del PJ en esta PASO.<\/p>\n<p>Ayer Aveiro hizo mejor elecci\u00f3n que en la primaria 2015, cuando el entonces Frente para la Victoria el intendente se reeleg\u00eda con el 46% de los votos, mientras que Cambia Mendoza sacaba 32%.<\/p>\n<p>Ahora, el candidato radical Gast\u00f3n Barcenilla ganaba la interna de Cambia Mendoza con el 15% de los votos (el frente ten\u00eda otro candidato, Marcelo L\u00f3pez, que obtuvo 12%, por lo que sumados sacaban menos votos que en 2015) y se posicionaba como el rival de Aveiro para la general.<\/p>\n<p>En la UCR destacaban el resultado en San Mart\u00edn, donde el Frente Cambia Mendoza qued\u00f3 abajo del intendente Jorge Gim\u00e9nez por una diferencia exigua, posible de revertir el 1 de setiembre, cuando se realizar\u00e1n las generales.<\/p>\n<p>As\u00ed como Bermejo fue a acompa\u00f1ar al que mejor le fue en la primaria,\u00a0en el b\u00fanker del principal precandidato de la UCR en San Mart\u00edn, el m\u00e9dico Ra\u00fal Rufeil, estaba el aspirante a vicegobernador de la UCR Mario Abed.<\/p>\n<p>Es cierto que Abed fue parte de la campa\u00f1a de Rufeil, pero al cierre de esta edici\u00f3n, Gim\u00e9nez obten\u00eda 18.750 votos y el adversario radical sacaba 17.023 votos (apenas 1.727 votos de diferencia). As\u00ed el \u00a0ex director del hospital Humberto Notti se transformaba en \u00a0la estrella UCR de la PASO.<\/p>\n<p>Un detalle: Gim\u00e9nez fue el \u00fanico intendente del frente Eleg\u00ed que enfrent\u00f3 a otros candidatos internos.\u00a0El entrenador de rugby Cristian Etem sac\u00f3 m\u00e1s de 20 puntos, lo que lo transforma en la sorpresa de la elecci\u00f3n.<\/p>\n<p>La pregunta que queda flotando es d\u00f3nde ir\u00e1n los votos que sac\u00f3 el adversario interno de Gim\u00e9nez en la general de setiembre. \u00bfSe quedar\u00e1n en el frente Eleg\u00ed? \u00bfSe los arrebatar\u00e1 Rufeil? Esa ser\u00e1 la gran pelea en el este.<\/p>\n<p>En la noche, en el Gobierno indicaban que el resultado\u00a0era el esperado en las cuatro comunas, aunque los interlocutores se mostraban satisfechos con la elecci\u00f3n de Rufeil.<\/p>\n<p>Esperanza radical. El diputado nacional Petri levanta la mano del candidato Rufeil. Lo abraza Abed.\u00a0| Patricio Caneo \/ Los Andes<br \/>\nEl otro resultado que resaltaban en el entorno de Cornejo es el que obtuvo Cambia Mendoza en Lavalle.\u00a0El n\u00famero que agitaban es el que obtuvo el intendente Roberto Righi en las PASO 2015, cuando ara\u00f1aba el 60% y Cambia Mendoza sacaba 22%.<\/p>\n<p>Ayer Righi obten\u00eda el 56% de los votos y los candidatos de Cambia Mendoza rondaba el 32%.<\/p>\n<p>El frente radical ten\u00eda dos aspirantes en carrera, el diputado provincial Jorge L\u00f3pez y el concejal Lucas Luppo.\u00a0L\u00f3pez fue el que se impuso en la interna con m\u00e1s de la mitad de los votos que obtuvo todo el frente.<\/p>\n<p>Por \u00faltimo, el resultado en\u00a0San Rafael\u00a0no dej\u00f3 lugar a las sorpresas. Con poco menos del 45% de los votos escrutados,\u00a0el frente Eleg\u00ed, con el intendente Emir F\u00e9lix como \u00fanico precandidato, lograba el 54% (35.9156 votos), mientras que Cambia Mendoza el 35% (23.161 sufragios).<\/p>\n<p>Esos 35 puntos se divid\u00edan entre cuatro candidatos que llevaba la coalici\u00f3n radical. El que m\u00e1s votos sacaba es el m\u00e9dico delegado del Ministerio de Salud en el sur, Abel Freidemberg (11.058), coloc\u00e1ndolo en la general de setiembre como el adversario de F\u00e9lix.<\/p>\n<p>La otra PASO comparable, la de 2015 (cuando se eligieron intendentes), dice que el actual intendente obten\u00eda su reelecci\u00f3n con el 49% de los votos, mientras que Cambia Mendoza sacaba el 40%. Lo que significa que F\u00e9lix ampli\u00f3 su diferencia.<\/p>\n<p>Protectora se qued\u00f3 sin el pase a la final<br \/>\nProtectora fuerza pol\u00edtica no tuvo el rendimiento esperado.\u00a0De ser la tercera fuerza en la elecci\u00f3n 2017, en este primer round no logr\u00f3 sumar el piso del 3% para pasar a la general de setiembre, en ninguno de los cuatro departamentos.<\/p>\n<p>La comparaci\u00f3n es injusta,\u00a0porque Ram\u00f3n no compet\u00eda,\u00a0y en 2017 no se eligieron intendentes, ni gobernador. Al cierre de esta edici\u00f3n,\u00a0el partido de Jos\u00e9 Luis Ram\u00f3n en Lavalle sac\u00f3 2,5%, en San Mart\u00edn el 1,57%, en San Rafael 1,26% y en Tunuy\u00e1n el 2%.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Ayer hubo PASO en San Mart\u00edn, Lavalle, Tunuy\u00e1n y San Rafael. El mejor resultado del frente Eleg\u00ed se dio en el departamento del Valle de Uco.<\/p>\n","protected":false},"author":2,"featured_media":89685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[31],"class_list":["post-89684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-politico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/89684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=89684"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/89684\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/89685"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=89684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=89684"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=89684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}