{"id":92203,"date":"2019-07-12T04:39:21","date_gmt":"2019-07-12T07:39:21","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=92203"},"modified":"2019-07-12T07:44:43","modified_gmt":"2019-07-12T10:44:43","slug":"en-mendoza-se-necesitan-10-sueldos-mas-que-hace-un-ano-para-una-casa","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/en-mendoza-se-necesitan-10-sueldos-mas-que-hace-un-ano-para-una-casa\/","title":{"rendered":"En Mendoza se necesitan 10 sueldos m\u00e1s que hace un a\u00f1o para una casa"},"content":{"rendered":"<p>El salario promedio en Mendoza hoy es de 27.315 pesos y se necesita acumular 116 meses de trabajo para alcanzar el sue\u00f1o de la casa propia.<\/p>\n<p>El sector inmobiliario est\u00e1 comenzando a ver \u201cse\u00f1ales de reactivaci\u00f3n\u201d, pero sin cr\u00e9ditos hipotecarios accesibles, la mayor\u00eda de las operaciones que se concretan tienen que ver con personas que decidieron \u201csacar la plata del colch\u00f3n\u201d. Esto \u00faltimo implica a\u00f1os de ahorros, y mucha disponibilidad de efectivo, equivalente a 116 salarios netos.<\/p>\n<p>Hace un a\u00f1o un relevamiento de Los Andes daba cuenta de que se necesitaba un promedio de 106 sueldos para comprar una casa en Mendoza,\u00a0considerando un\u00a0inmueble de 80 m2 cubiertos en un terreno de 200 m2 en localidades como barrio Parque de Godoy Cruz, \u00a0Dorrego de Guaymall\u00e9n, o en la cuarta secci\u00f3n.\u00a0En ese momento, una vivienda de esas caracter\u00edsticas costaba en promedio $ 2 millones, pero desde julio de 2018 a la fecha hubo una gran devaluaci\u00f3n que elev\u00f3 en un 60% el precio de las propiedades en pesos, y los salarios no se ajustaron en la misma medida.<\/p>\n<p>De acuerdo con datos de la consultora en econom\u00eda Evaluecon, el salario promedio en Mendoza alcanza hoy un valor de $ 27.500. En tanto, los valores de las propiedades, por fuera del microcentro mendocino, y en la periferia de los centros de cada departamento, se elev\u00f3 de $ 2.000.000 a no menos de $ 3.200.000. Esto significa que hoy se deber\u00eda trabajar durante 116 meses (poco m\u00e1s de nueve a\u00f1os y medio) para comprar una casa de las caracter\u00edsticas mencionadas, sin destinar un solo peso a otros gastos.<\/p>\n<p>Cabe aclarar que el salario considerado corresponde a una estimaci\u00f3n de la consultora e incluye tanto salarios privados como p\u00fablicos a valores netos, de bolsillo.<\/p>\n<p>Para Mendoza todav\u00eda no hay n\u00fameros oficiales sobre salario promedio actual, pero de acuerdo con una estimaci\u00f3n que realiz\u00f3 el economista de Fundaci\u00f3n Mediterr\u00e1nea Ieral Mendoza), en base a las variaciones porcentuales sobre salario publicado por el Ministerio de Producci\u00f3n y Trabajo, y al que public\u00f3 hasta abril el Indec, en la provincia podr\u00eda considerarse un salario privado promedio de $ 31.240 (Indec) o de $ 31.959 (ministerio).<\/p>\n<p>En este caso la estimaci\u00f3n arroja valores brutos, pero si se considera un 17% de aportes para trabajadores registrados, el promedio de bolsillo ser\u00eda $ 27.315, un n\u00famero similar al calculado por Vargas.<\/p>\n<p>El precio de los inmuebles<br \/>\nActualmente es posible encontrar viviendas en el mercado de compra-venta, con precios que rondan los $ 2.000.000, pero la oferta se reduce mayormente a departamentos de dos dormitorios, o casas chicas con poco terreno y en zonas alejadas.<\/p>\n<p>De acuerdo con\u00a0Estanislao Puelles, presidente del Colegio de Corredores P\u00fablicos Inmobiliarios, la devaluaci\u00f3n del a\u00f1o pasado fren\u00f3 las operaciones e hizo que se produjera una distorsi\u00f3n en los precios\u00a0y en la cantidad de sueldos necesarios para adquirir un inmueble, agrandando la brecha.<\/p>\n<p>\u201cEl cr\u00e9dito inmobiliario desde fines de 2018 se fren\u00f3 absolutamente. Hoy no hay operaciones de ese tipo y las pocas que se realizan se hacen con ahorros o plata del colch\u00f3n. Eso est\u00e1 empezando a dar se\u00f1ales de reactivaci\u00f3n\u201d, agreg\u00f3.<\/p>\n<p>Seg\u00fan Puelles, en materia de inversiones sobresalen las operaciones en boca de pozo, que no suelen estar relacionadas con la necesidad de las familias, sino con una pretensi\u00f3n de renta futura. \u201cHoy un departamento para un matrimonio con uno o dos hijos puede costar $ 2.500.000 y si buscan casas de 2, o 3 dormitorios, tienen que pensar en gastar de $ 3.000.000 para arriba\u201d, dijo.<\/p>\n<p>Es que mientras que en 2018 era posible encontrar viviendas por $ 2.000.000, a la fecha las propiedades se actualizaron en alrededor de un 60% (en pesos), y perdieron valor en d\u00f3lares. \u201cLa primera reacci\u00f3n ante una devaluaci\u00f3n es paralizar las operaciones, despu\u00e9s quienes tienen operaciones en d\u00f3lares deben adecuarlos, porque hasta que no bajan los precios no venden, y quienes tienen operaciones en pesos, los suben un poco\u201d, cerr\u00f3 el titular del Colegio.<\/p>\n<p><strong>Valores variables<\/strong><br \/>\nEl corredor inmobiliario Miguel \u00c1ngel Astorga, se refiri\u00f3 al precio de las propiedades en m\u00b2, los cuales var\u00edan seg\u00fan diferentes factores, como ubicaci\u00f3n o servicios, pero que rondan \u00a0$ 25.000 (solo construcci\u00f3n, sin terreno).\u00a0As\u00ed, una familia que piensa en una casa est\u00e1ndar tipo IPV, deber\u00eda considerar que solo por la vivienda deber\u00e1 invertir $ 1.350.000 (54 m\u00b2), que se van a $ 2 millones con el terreno. Si la misma casa tuviera terminaciones finas, el precio por m\u00b2 se ir\u00eda a $ 30.000.<\/p>\n<p>\u201cEl 95% de las personas busca viviendas con cochera y esto eleva el precio del inmueble en un rango de entre $ 150.000 y $ 200.000 m\u00e1s\u201d, se\u00f1al\u00f3 Astorga.<\/p>\n<p>El estado de la propiedad, la antig\u00fcedad, el tipo de construcci\u00f3n, los servicios y las v\u00edas de comunicaci\u00f3n, son otros de los factores que elevan o bajan el precio de una propiedad, as\u00ed como la oferta disponible de viviendas similares. Seg\u00fan el inmobiliario Santiago Deb\u00e9 los precios pueden ser m\u00e1s \u201cparejos\u201d en los departamentos, en donde es posible encontrar viviendas por $ 2.500.000.<\/p>\n<p>\u201cUna casa en un barrio regular puede costar $ 3.000.000. En estas pesa el terreno, en cambio en los d\u00faplex de 80 m\u00b2 o 100 m\u00b2, los valores son m\u00e1s est\u00e1ndar. Se han hecho muchos barrios en los \u00faltimos a\u00f1os, pero los inversores son pocos y mientras se mantengan intereses de renta financiera en el 40%, comprar una casa para volcarla al mercado locatario al 0,05% mensual ser\u00e1 seguro, pero no rentable\u201d, cerr\u00f3 el empresario.<\/p>\n<h6>Fuente: Los Andes<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El salario promedio en Mendoza hoy es de 27.315 pesos y se necesita acumular 116 meses de trabajo para alcanzar el sue\u00f1o de la casa propia.<\/p>\n","protected":false},"author":2,"featured_media":92204,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[31],"class_list":["post-92203","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/92203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=92203"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/92203\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/92204"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=92203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=92203"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=92203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}