{"id":92573,"date":"2019-07-24T07:10:13","date_gmt":"2019-07-24T10:10:13","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=92573"},"modified":"2019-07-24T07:10:13","modified_gmt":"2019-07-24T10:10:13","slug":"cerraron-75-bodegas-mendocinas-en-los-ultimos-siete-anos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/cerraron-75-bodegas-mendocinas-en-los-ultimos-siete-anos\/","title":{"rendered":"Cerraron 75 bodegas mendocinas en los \u00faltimos siete a\u00f1os"},"content":{"rendered":"<p>La crisis econ\u00f3mica no dej\u00f3 sectores sin afectar. En los \u00faltimos siete a\u00f1os cerraron 75 bodegas en Mendoza, seg\u00fan el \u00faltimo informe del Instituto Nacional de Vitivinicultura.<\/p>\n<p>Seg\u00fan explic\u00f3 Marcelo Bustos Herrera para el programa\u00a0Conexi\u00f3n Agro\u00a0de\u00a0Radio Nihuil,\u00a0desde el 2012 unas 120 bodegas cerraron en todo el pa\u00eds\u00a0o fueron absorbidas por otras m\u00e1s grandes.<\/p>\n<p>En 2012, el informe indica que hab\u00eda 1300 bodegas y actualmente hay 1199en las 16 provincias que producen vino.<\/p>\n<p>La situaci\u00f3n de\u00a0Mendoza\u00a0no es diferente.\u00a0En el 2012 estaban inscriptas 948 bodegas y actualmente hay 873.\u00a0Solamente en cuatro departamentos aument\u00f3 la cantidad de establecimientos, en dos se mantuvo y en el resto disminuy\u00f3 el n\u00famero de bodegas.<\/p>\n<p>La zona que m\u00e1s preocupa, seg\u00fan datos del informe es la que conforman los departamentos del Este.\u00a0En siete a\u00f1os cerraron 65 bodegas de San Mart\u00edn, Rivadavia, Jun\u00edn y Santa Rosa. Solo La Paz mantuvo su \u00fanica bodega.<\/p>\n<p>San Juan tambi\u00e9n ha sufrido el cierre de bodegas, sumando 56 en los \u00faltimos a\u00f1os.\u00a0 En R\u00edo Negro y La Rioja tambi\u00e9n se registraron bajas.<\/p>\n<p>Solamente tres provincias sumaron establecimientos: Salta, C\u00f3rdoba y Tucum\u00e1n.<\/p>\n<h6>Fuente: Uno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La crisis econ\u00f3mica no dej\u00f3 sectores sin afectar.\u00a0En los \u00faltimos siete a\u00f1os cerraron 75 bodegas en Mendoza, seg\u00fan el \u00faltimo informe del\u00a0Instituto Nacional de Vitivinicultura.<\/p>\n","protected":false},"author":2,"featured_media":92574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[31],"class_list":["post-92573","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/92573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=92573"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/92573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/92574"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=92573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=92573"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=92573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}