{"id":97728,"date":"2019-12-27T08:09:40","date_gmt":"2019-12-27T11:09:40","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=97728"},"modified":"2019-12-27T08:09:40","modified_gmt":"2019-12-27T11:09:40","slug":"mendoza-suspende-la-reforma-de-la-ley-de-mineria-que-afectaba-el-agua","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/mendoza-suspende-la-reforma-de-la-ley-de-mineria-que-afectaba-el-agua\/","title":{"rendered":"Mendoza suspende la reforma de la ley de miner\u00eda que afectaba el agua"},"content":{"rendered":"<p>\u00abNo voy a reglamentar la ley\u00bb, anunci\u00f3 ayer el gobernador Rodolfo Su\u00e1rez. \u00abLo que m\u00e1s quiero es el cuidado del agua\u00bb, sostuvo.<\/p>\n<p>El gobernador de Mendoza, Rodolfo Su\u00e1rez, anunci\u00f3 ayer que no reglamentar\u00e1 la ley 9.209, que facilita la explotaci\u00f3n minera en la provincia, y se iniciar\u00e1 un di\u00e1logo abierto para lograr el consenso social porque, dijo, lo que m\u00e1s quiere es \u00abel cuidado del agua\u00bb.<\/p>\n<p>La ley 9.209 corresponde a la modificaci\u00f3n de la 7.722 original, dictada durante el gobierno provincial de Julio Cobos. \u00abNo voy a reglamentar la ley, no estar\u00e1 vigente\u00bb, afirm\u00f3 Su\u00e1rez, y anunci\u00f3 que se abrir\u00e1 un di\u00e1logo con distintas organizaciones y la iglesia \u00abpara una gran convocatoria al di\u00e1logo e informaci\u00f3n de la gente\u00bb.<\/p>\n<p>\u00abEl primer deber que tiene un gobernador es garantizar la paz social\u00bb, indic\u00f3 el mandatario en conferencia de prensa realizada ayer al mediod\u00eda en Casa de Gobierno. Asimismo, Su\u00e1rez critic\u00f3 los \u00abhechos de violencia, cortes de ruta, quejas de ciertos sectores, algunos muy violentos\u00bb y record\u00f3 que hasta \u00abfuncionarios recibimos amenazas y hostigamientos\u00bb.<\/p>\n<p>\u00abLa obligaci\u00f3n del gobernador es mantener la paz social\u00bb, afirm\u00f3, y llam\u00f3 a reflexionar en la actual situaci\u00f3n en la que \u00abMendoza tiene un modelo econ\u00f3mico que hace tiempo no crece ni genera riqueza, y donde hay un 40 por ciento de la poblaci\u00f3n por debajo de la pobreza, que no comen o no pueden mandar a sus chicos al colegio y la est\u00e1n pasando muy mal\u00bb.<\/p>\n<p>\u00abEn la campa\u00f1a dije que \u00edbamos a generar empleo para esa gente que la est\u00e1 pasando muy mal, y lo haremos haciendo las cosas bien, y preservando un bien tan preciado como es el agua\u00bb, afirm\u00f3.<\/p>\n<p>La aprobaci\u00f3n por la legislatura provincial de la reforma de la ley 7.722 -la cual limitaba el uso de sustancias t\u00f3xicas en la actividad minera- estuvo precedida y seguida de manifestaciones multitudinarias en distintos puntos de la provincia. Una marcha que tuvo lugar el lunes en la capital mendocina deriv\u00f3 en el enfrentamiento de los manifestantes con las fuerzas de seguridad. Su\u00e1rez indic\u00f3 que este tipo de normas deben contar con legitimidad, \u00abque se la da el pueblo mendocino\u00bb.<\/p>\n<p>\u00abReconozco que esto ha tomado otra dimensi\u00f3n. El miedo ha calado en la sociedad y muchos que me han votado me manifestaron sus temores. Han mentido mucho y han logrado instalar el miedo en la sociedad\u00bb, afirm\u00f3.<\/p>\n<p>El gobernador argument\u00f3 que en Mendoza \u00abse pueden generar m\u00e1s de 50 mil puestos de trabajo sin afectar ninguna cuenca de r\u00edo\u00bb, aunque puntualiz\u00f3 que \u00abno se va a avanzar en ning\u00fan lugar donde no haya consenso social\u00bb.<\/p>\n<p>Greenpeace y otros grupos ambientalistas y de izquierda hab\u00edan denunciado que \u00abla Legislatura provincial, de manera expr\u00e9s, modific\u00f3 negativamente la ley provincial 7.722 que proteg\u00eda el agua prohibiendo el uso de sustancias t\u00f3xicas\u00bb en Mendoza, la cual \u00abten\u00eda esa legislaci\u00f3n que la convert\u00eda en vanguardia mundial por la protecci\u00f3n sobre su naturaleza y ambiente\u00bb.<\/p>\n<p>La modificaci\u00f3n aprobada \u00abpermite el uso de \u00e1cido sulf\u00farico, cianuro y otros t\u00f3xicos en el desarrollo de la megaminer\u00eda, lo que generar\u00e1 el faltante y la contaminaci\u00f3n del agua de la provincia\u00bb, sostuvo Greenpeace.<\/p>\n<p>\u00abEl agua es de todos\u00bb<\/p>\n<p>En tanto, el ministro de Ambiente y Desarrollo Sostenible de la Naci\u00f3n, Juan Cabandi\u00e9, asegur\u00f3 ayer, en relaci\u00f3n con la reforma de la ley mendocina de miner\u00eda que \u00abtenemos claro que la Constituci\u00f3n Nacional establece que estos recursos son de las provincias, y la ley 7.722 es un tema de Mendoza, pero el agua es un tema de todos\u00bb.<\/p>\n<p>En medio de la controversia que se gener\u00f3 en torno a este tema, el gobernador Rodolfo Su\u00e1rez anunci\u00f3 este mediod\u00eda que suspender\u00e1 la reglamentaci\u00f3n de la ley minera, y que se generar\u00e1 un di\u00e1logo abierto \u00absin generaci\u00f3n de miedos, garantizando la paz social, porque lo que m\u00e1s quiero es cuidar el agua\u00bb.<\/p>\n<p>Cabandi\u00e9, en una entrevista radial en AM 530 Somos Radios, afirm\u00f3 que \u00abel presidente y todos en general estamos muy preocupados\u00bb, y recalc\u00f3 sobre la movilizaci\u00f3n y la concientizaci\u00f3n de la ciudadan\u00eda de la provincia: \u00abMe parece que marca un camino que, evidentemente, no tiene consenso en la sociedad mendocina\u00bb.<\/p>\n<p>\u00abHay una cuenca h\u00eddrica -explic\u00f3 el ministro- que es la del Desaguadero, la cuenca del Atuel, donde hay varias provincias. Por lo tanto, mi competencia como ministro de Ambiente est\u00e1 en cuidar los aspectos ambientales del agua\u00bb.<\/p>\n<h6>Fuente: La Capital<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>\u00abNo voy a reglamentar la ley\u00bb, anunci\u00f3 ayer el gobernador Rodolfo Su\u00e1rez. \u00abLo que m\u00e1s quiero es el cuidado del agua\u00bb, sostuvo.<\/p>\n","protected":false},"author":2,"featured_media":97729,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[31],"class_list":["post-97728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-mendoza"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/97728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=97728"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/97728\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/97729"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=97728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=97728"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=97728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}