{"id":97966,"date":"2020-01-06T05:56:43","date_gmt":"2020-01-06T08:56:43","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=97966"},"modified":"2020-01-06T08:01:50","modified_gmt":"2020-01-06T11:01:50","slug":"chubut-esta-asediada-por-sus-problemas-de-endeudamiento","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/chubut-esta-asediada-por-sus-problemas-de-endeudamiento\/","title":{"rendered":"Chubut est\u00e1 asediada por sus problemas de endeudamiento"},"content":{"rendered":"<p>Esta provincia junto a Jujuy y Buenos Aires son las tres jurisdicciones que se encuentran en situaci\u00f3n cr\u00edtica por sus altos endeudamientos en d\u00f3lares. El 80% de los ingresos de Chubut est\u00e1 destinado al pago de sus deudas. En 2021 se duplicar\u00e1 el vencimiento de su deuda y se volver\u00e1 inviable para el Gobierno de Mariano Arcioni.<\/p>\n<p>Chubut arrastra problemas financieros desde hace a\u00f1os. El grueso de su deuda est\u00e1 garantizado con regal\u00edas petroleras, pero la caja no alcanza para enfrentar los vencimientos de 2020 y el gobernador Mariano Arcioni lo reconoci\u00f3 incluso antes de las elecciones cuando se convirti\u00f3 en la primera provincia en anunciar la reestructuraci\u00f3n de su deuda.<\/p>\n<p>Los datos de 2018 detallan que el grueso de la deuda supera el 80% de los ingresos provinciales y que durante este a\u00f1o deber\u00e1 enfrentar pagos por 49 millones de deuda con el mercado. En tanto, en el 2021 deber\u00e1 abonar 114 millones y en el 2022 pagar\u00e1 108 millones. El problema nace en los casi 30 millones de d\u00f3lares trimestrales que viene pagando y que a partir de 2021, al duplicarse el vencimiento de capitales, se volver\u00e1 inviable para las arcas provinciales. Es que las necesidades de financiamiento de Chubut en 2019 eran de 12 puntos porcentuales de sus ingresos corrientes entre gastos corrientes, gastos de capital y servicios de deuda.<\/p>\n<p>Otra de las provincias con dificultades econ\u00f3micas es Buenos Aires de quien enfrenta vencimientos por 169.000 millones de d\u00f3lares para este a\u00f1o. Esto eleva las necesidades de financiamiento a algo m\u00e1s de $10 por cada $100 que se produce en la provincia (PGB), lo que la vuelve impagable tal y como advirti\u00f3 la consultora Elypsis en uno de sus \u00faltimos informes.<\/p>\n<p>De la deuda denominada en d\u00f3lares, en 2020, el gobierno de Axel Kicillof deber\u00eda pagar casi 2.100 d\u00f3lares, alrededor de 850 millones de ellos a bonistas y la mayor parte de los mismos en la primera mitad del a\u00f1o. Por esa raz\u00f3n es la provincia con la peor situaci\u00f3n financiera: en t\u00e9rminos de sus ingresos, la deuda provincial asciende al 84%, pero adem\u00e1s el 77% est\u00e1 en d\u00f3lares y es la m\u00e1s voluminosa de todas las deudas provinciales. Por eso el mercado espera que pr\u00f3ximamente Kicillof llame a una reestructuraci\u00f3n o directamente defaultee.<\/p>\n<p>Seg\u00fan detalla La Pol\u00edtica Online, Jujuy es otra de las provincias que padece los vencimientos de su deuda. Gerardo Morales, al igual que Mar\u00eda Eugenia Vidal, fue uno de los gobernadores que m\u00e1s emiti\u00f3 deuda durante la gesti\u00f3n de Mauricio Macri dejando a Jujuy con 1.700 millones de d\u00f3lares de deuda y el mayor ratio de deuda en relaci\u00f3n a los ingresos: 87%; de los cuales adem\u00e1s el 85% est\u00e1 en d\u00f3lares. Sin embargo, este 2020 no tiene que pagar capital, solo 9 millones de d\u00f3lares de intereses en septiembre por el bono Jujuy 2022.<\/p>\n<p>PROVINCIAS MAS ALIVIADAS<\/p>\n<p>El \u00faltimo ranking del \u00e1rea de investigaciones de la banca Barclays estipula que, con los mismos 12 puntos de necesidades financieras por encima de los ingresos, se ubicaba la provincia de La Rioja, aunque como no tiene vencimientos de deuda en 2020 sus desbalances no la empujan al default como s\u00ed a Chubut y a Buenos Aires.<\/p>\n<p>Mendoza y C\u00f3rdoba no tienen ratios de deuda sobre ingresos exorbitantes, pero tampoco est\u00e1n en condiciones favorables ya que dependen casi exclusivamente de que el ministro de Econom\u00eda de la Naci\u00f3n, Mart\u00edn Guzm\u00e1n, pueda reabrir en el corto plazo los mercados voluntarios de deuda antes de que se les vengan los vencimientos grandes.<\/p>\n<p>El caso de C\u00f3rdoba puede ser la sorpresa de 2021 cuando los vencimientos de capital se multipliquen por veinte y pasen de los 38 millones anuales de 2019 y 2020 a nada menos que 763 millones. Ya de por s\u00ed, en el ranking de Barclays las necesidades financieras totales ascienden a 11 puntos de sus ingresos corrientes. En tanto que Mendoza deber\u00e1 atender vencimientos de capital de 167 millones de d\u00f3lares anuales entre 2022 y 2024, pero sus necesidades financieras son moderadas en relaci\u00f3n al resto de las provincias (5,5% de los ingresos).<\/p>\n<p>En ambos casos, recortando toda la obra p\u00fablica y renovando la deuda intra sector p\u00fablico, estas provincias logran ser superavitarias por 6,7 y 5,3 puntos de sus ingresos, lo que en el corto plazo les permitir\u00eda mantener alejado al fantasma del default.<\/p>\n<h6>Fuente: Patag\u00f3nico<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Esta provincia junto a Jujuy y Buenos Aires son las tres jurisdicciones que se encuentran en situaci\u00f3n cr\u00edtica por sus altos endeudamientos en d\u00f3lares.<\/p>\n","protected":false},"author":2,"featured_media":97967,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[65],"tags":[14],"class_list":["post-97966","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincias","tag-chubut"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/97966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=97966"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/97966\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/97967"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=97966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=97966"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=97966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}