{"id":98120,"date":"2020-01-13T06:55:28","date_gmt":"2020-01-13T09:55:28","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=98120"},"modified":"2020-01-13T06:55:28","modified_gmt":"2020-01-13T09:55:28","slug":"estados-unidos-aplica-nuevas-sanciones-a-cuba","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/estados-unidos-aplica-nuevas-sanciones-a-cuba\/","title":{"rendered":"Estados Unidos aplica nuevas sanciones a Cuba"},"content":{"rendered":"<p>La administraci\u00f3n Trump busca obstaculizar el acceso del gobierno de D\u00edaz Canel \u201ca moneda fuerte a trav\u00e9s de los viajeros estadounidenses\u201d.<\/p>\n<p>El secretario de Estado de EEUU Mike Pompeo empieza el comunicado en primera persona: \u201cEn el d\u00eda de hoy, a pedido m\u00edo,\u00a0el Departamento de Transporte (DOT)suspendi\u00f3 todos los vuelos ch\u00e1rter p\u00fablicos entre Estados Unidos y destinos cubanos distintos del Aeropuerto Internacional Jos\u00e9 Mart\u00ed de La Habana\u2026\u201d La nota es del 10 de enero y aclara que conceder\u00e1 un per\u00edodo de sesenta d\u00edas para que las compa\u00f1\u00edas a\u00e9reas discontin\u00faen sus vuelos hacia Cuba.<\/p>\n<p>La medida le hace un torniquete m\u00e1s a la econom\u00eda de la isla para secarla de recursos, el objetivo que se plante\u00f3 Donald Trump desde que lleg\u00f3 a la casa Blanca. Si a escala planetaria se consolida la mano dura del gendarme mundial \u2013 como qued\u00f3 demostrado con Ir\u00e1n-, su vecino integra el ranking de pa\u00edses sancionables, aunque por ahora en un nivel punitivo distinto al de Teher\u00e1n. Sin drones, sin bombas, sin asesinatos selectivos. S\u00ed con la asfixia a su comercio, al acceso de divisas restringidas hace d\u00e9cadas y ahora al turismo receptivo cubano en sus diferentes ciudades con excepci\u00f3n de la capital.<\/p>\n<p>Nueve aeropuertos en Cuba ya no recibir\u00e1n vuelos ni viajeros desde Estados Unidos en un par de meses. Pompeo, una especie de ejecutor imperial, lo dej\u00f3 muy claro en su mensaje para la prensa publicado en todas las cuentas del Departamento de Estado: \u201cLa medida impedir\u00e1 que el r\u00e9gimen cubano se beneficie con la ampliaci\u00f3n del servicio de vuelos ch\u00e1rter tras la medida del 25 de octubre de 2019 que suspendi\u00f3 los servicios a\u00e9reos comerciales programados hacia aeropuertos de Cuba distintos al de La Habana. La medida de hoy contribuir\u00e1 a limitar la posibilidad del r\u00e9gimen de obtener beneficios econ\u00f3micos, que emplea para financiar la represi\u00f3n constante contra el pueblo cubano y su apoyo inadmisible al dictador Nicol\u00e1s Maduro en Venezuela\u201d.<\/p>\n<p>M\u00e1s adelante el texto se\u00f1ala, en un tono mon\u00f3tono y repetitivo \u2013 cinco veces se\u00f1ala la palabra medida \u2013 que se busca \u201cobstaculizar\u201d el acceso del gobierno de Miguel D\u00edaz Canel \u201ca moneda fuerte a trav\u00e9s de los viajeros estadounidenses\u201d. Nada dice de la violaci\u00f3n de los derechos a viajar libremente de esos potenciales visitantes, ni de los problemas econ\u00f3micos y de demoras que les ocasionar\u00e1 la pol\u00edtica de acentuamiento del bloqueo. Para ir hacia Santiago de Cuba, en el Oriente, tendr\u00e1n que pasar antes por La Habana, por citar un solo ejemplo.\u00a0Las compa\u00f1\u00edas estadounidenses que se ver\u00e1n afectadas en su negocio son American Airlines y JetBlue que viajan a Camag\u00fcey, Holgu\u00edn y Villa Clara entre otros destinos.<\/p>\n<p>Pero adem\u00e1s, el comunicado de Pompeo se\u00f1ala que \u201ca solicitud m\u00eda, el DOT establecer\u00e1 un tope m\u00e1ximo adecuado a la cantidad de vuelos ch\u00e1rter m\u00e1ximos permitidos que tengan como destino el Aeropuerto Internacional Jos\u00e9 Mart\u00ed\u201d. O sea, habr\u00e1 un n\u00famero restringido de viajes de ese tipo que posibilitan a los turistas beneficios de proximidad con sus destinos y a veces en precios.<\/p>\n<p>La medida que tom\u00f3 el gobierno de Trump fue reproducida por el\u00a0Washington Post\u00a0y la agencia AP en EEUU y tambi\u00e9n en la isla por el sitio Cubadebate.\u00a0Cuando se anunci\u00f3 la decisi\u00f3n de restringir los vuelos regulares de aerol\u00edneas comerciales en octubre de 2019, la congresista estadounidense B\u00e1rbara Lee (dem\u00f3crata por California) la cuestion\u00f3 porque \u201cdestruye cualquier relaci\u00f3n entre nuestros pa\u00edses\u201d.\u00a0Asimismo, dijo que \u201cestas pol\u00edticas aislacionistas y atrasadas da\u00f1ar\u00e1n a cubanos y estadounidenses por igual\u201d. Otro dem\u00f3crata, pero por Massachusetts, el diputado James McGovern hab\u00eda tildado a la restricci\u00f3n de \u201cest\u00fapido truco pol\u00edtico\u201d.<\/p>\n<p>No solo desde el Parlamento provinieron las cr\u00edticas. La instituci\u00f3n Cooperaci\u00f3n en Educaci\u00f3n M\u00e9dica con Cuba describi\u00f3 a la prohibici\u00f3n como \u201cdeplorable\u201d. Se trata de una entidad fundada en 1997 y que est\u00e1 radicada en Oakland, California. MEDICC trabaja para promover la colaboraci\u00f3n entre Estados Unidos y Cuba en el campo de la Salud.<\/p>\n<p>Cuando Trump anunci\u00f3 el endurecimiento de sus pol\u00edticas hacia Cuba en junio de 2017 lo hizo desde Miami, la ciudad santa de la di\u00e1spora, tan anticastrista como alineada con los halcones Marco Rubio, Ileana Ross Lehtinen y Bob Men\u00e9ndez, entre otros congresistas del lobby anticubano. Esos dirigentes juegan de local ah\u00ed, en la principal ciudad de la Florida, donde a lo largo de la historia se han urdido todo tipo de conspiraciones para derribar a Fidel Castro primero y desestabilizar a su hermano Ra\u00fal despu\u00e9s. Esa l\u00ednea pol\u00edtica contin\u00faa ahora contra D\u00edaz Canel y le ha permitido al magnate devenido presidente de EEUU desmontar cada uno de los puntos de la pol\u00edtica bilateral que fijaron a fines de 2014 Barack Obama y el menor de los Castro, quien dej\u00f3 de ser jefe de Estado en abril de 2018.<\/p>\n<p>Las sanciones aplicadas a Cuba por EEUU anunciadas por el Departamento de Estado mostraron una perlita el viernes pasado. La portavoz que depende de Pompeo, oficial activa de la Reserva Naval de Estados Unidos y colaboradora en temas de seguridad nacional de Fox News, Morgan Ortagus, dio uno de sus habituales mensajes, esta vez referido a Cuba. Lo hizo para hablar de la situaci\u00f3n de Jos\u00e9 Daniel Ferrer Garc\u00eda, un disidente y militante de los Derechos Humanos para EEUU; un contrarrevolucionario para la isla que fue detenido por secuestrar y golpear a otro ciudadano cubano el 1\u00b0 de octubre.<\/p>\n<p>Cuando Ortagus inform\u00f3 lo que pasaba con el presunto disidente, tras cumplirse 100 d\u00edas de su detenci\u00f3n, tuvo m\u00e1s de un fallido. Ella hab\u00eda dicho que es torturado en prisi\u00f3n y que se le proh\u00edbe el contacto con la familia. Pero el gobierno lo film\u00f3 para refutar las acusaciones una por una. Se lo ve saludable y conversando amigablemente en el lugar de detenci\u00f3n con su parentela, como publicaron Cubadebate y otros medios. La vocera del Departamento de Estado adem\u00e1s se permiti\u00f3 mencionar a un ex presidente cubano como si a\u00fan siguiera en el ejercicio del cargo. Aludi\u00f3 varias veces al \u201cr\u00e9gimen de Castro\u201d, como si en Cuba todav\u00eda gobernaran Fidel o Ra\u00fal. Una producci\u00f3n de sentido en la que hizo \u201cun llamado\u201d para que liberen al acusado, una y otra vez. \u00bfA qui\u00e9n? \u201cAl r\u00e9gimen de Castro\u201d.<\/p>\n<h6>Fuente: P\u00e1gina 12<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La administraci\u00f3n Trump busca obstaculizar el acceso del gobierno de D\u00edaz Canel \u201ca moneda fuerte a trav\u00e9s de los viajeros estadounidenses\u201d.<\/p>\n","protected":false},"author":2,"featured_media":98121,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[22],"tags":[57],"class_list":["post-98120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-el-mundo","tag-el-mundo"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=98120"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/98121"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=98120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=98120"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=98120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}