{"id":98126,"date":"2020-01-13T07:05:47","date_gmt":"2020-01-13T10:05:47","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=98126"},"modified":"2020-01-13T07:05:47","modified_gmt":"2020-01-13T10:05:47","slug":"rosario-esta-en-el-podio-de-las-ciudades-con-el-metro-cuadrado-mas-caro","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/rosario-esta-en-el-podio-de-las-ciudades-con-el-metro-cuadrado-mas-caro\/","title":{"rendered":"Rosario est\u00e1 en el podio de las ciudades con el metro cuadrado m\u00e1s caro"},"content":{"rendered":"<p>Alquilar en Rosario suele ser un problema para muchos, y comprar la vivienda propia suena a utop\u00eda para cualquier familia de clase media. Un relevamiento reciente confirm\u00f3 que la ciudad se encuentra entre las tres m\u00e1s caras del pa\u00eds en el precio del metro cuadrado.<\/p>\n<p>El estudio elaborado por Mercado Libre tom\u00f3 en consideraci\u00f3n 150.000 publicaciones activas en toda la Argentina con el objetivo de analizar \u00ablas variaciones en t\u00e9rminos de ventas, alquileres y rentabilidad\u00bb. Rosario figura como la tercera ciudad m\u00e1s cara del pa\u00eds para la compra de inmuebles y la quinta en lo que respecta a alquileres.<\/p>\n<p>El R\u00e1nking\u00a0de Precios de venta por metro cuadrado est\u00e1 encabezado por la Ciudad de Buenos Aires, cuyo valor promedio en d\u00f3lares por metro cuadrado es de u$s 2.792; le sigue Mar del Plata, cuyo m2 vale u$s 1.864. En tercer lugar figura Rosario, con un promedio de u$s 1786 por m2.<\/p>\n<p>En el caso de los alquileres, el podio tambi\u00e9n est\u00e1 liderado por CABA, con un valor promedio de renta de $16.924. Mar del Plata, al igual que en venta, ocupa el segundo lugar, con alquileres promedio de $10.933. En tercer lugar est\u00e1 La plata, donde se puede rentar una vivienda a un valor promedio de $ 10.933. En alquileres, Rosario est\u00e1 en quinto lugar, con un valor promedio de $8.914.<\/p>\n<p>Seg\u00fan el informe, la raz\u00f3n por la cual Rosario ocupa la \u00faltima posici\u00f3n tiene relaci\u00f3n con su menor ajuste interanual, de s\u00f3lo un 24%, muy por debajo de la inflaci\u00f3n en el \u00faltimo a\u00f1o. Esto se debe a una importante oferta y competencia en el mercado de alquileres, ya que la demanda es menor que en el resto de las ciudades analizadas generando un contexto muy competitivo que hace dif\u00edcil subir los precios. De esta manera, la ciudad tambi\u00e9n tuvo la Rentabilidad Bruta Anual m\u00e1s baja del tercer trimestre con un 2,21%.<\/p>\n<p>En cuanto a la ciudades m\u00e1s baratas, la ganadora indiscutible fue San Miguel de Tucum\u00e1n, cuyos precios equivalen al 40 por ciento de los valores que se manejan en Buenos Aires, calculando una diferencia del 151%.<\/p>\n<h6>Fuente: Casilda Plus<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Alquilar en Rosario suele ser un problema para muchos, y comprar la vivienda propia suena a utop\u00eda para cualquier familia de clase media.<\/p>\n","protected":false},"author":2,"featured_media":98127,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[10],"class_list":["post-98126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-economico","tag-santa-fe"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=98126"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98126\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/98127"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=98126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=98126"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=98126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}