{"id":98438,"date":"2020-01-20T08:18:49","date_gmt":"2020-01-20T11:18:49","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=98438"},"modified":"2020-01-20T08:18:49","modified_gmt":"2020-01-20T11:18:49","slug":"se-viene-el-festival-del-poncho-molinos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/se-viene-el-festival-del-poncho-molinos\/","title":{"rendered":"Se viene el Festival del Poncho, Molinos"},"content":{"rendered":"<p>El intendente de Molinos, Walter Chocobar, cont\u00f3 a El Tribuno acerca de los artistas que integran la cartelera del megafestival folcl\u00f3rico a realizarse en ese lugar del Valle Calchaqu\u00ed el pr\u00f3ximo 24 y 25 del corriente, y anticip\u00f3 que a principios de la pr\u00f3xima semana recibir\u00e1n y agasajar\u00e1n al primer turista que llegue a la localidad.<\/p>\n<p>Ya son 37 ediciones del Festival del Poncho, Doma y Folclore. \u00bfQu\u00e9 atractivos presenta este a\u00f1o?<\/p>\n<p>S\u00ed, la verdad que es un festival que se ha consolidado a trav\u00e9s del tiempo. Este a\u00f1o hicimos un gran esfuerzo para acercar a nuestra comunidad y ofrecer a los turistas un espect\u00e1culo art\u00edstico de primer nivel. El viernes 24, por ejemplo, actuar\u00e1n Atemporal, Lapachos, Llokallas, Agustina Nery, Alma Chaque\u00f1a, Guitarreros y Los Nombradores del Alba. Al d\u00eda siguiente subir\u00e1n al escenario Matacos, Chirettes, L\u00e1zaro Caballero, Los 4 de C\u00f3rdoba, Ahyre y, engalanando Molinos, Jorge Rojas. Se sumar\u00e1n tambi\u00e9n cuerpos de baile y artistas locales.<\/p>\n<p>Como se puede apreciar, se trata de una propuesta imperdible. Y un dato important\u00edsimo, la entrada es muy, pero muy accesible, porque queremos que sea una fiesta popular. La entrada general ser\u00e1 de 300 pesos. Como queremos que sea una experiencia inolvidable, contratamos un sonido a la altura del nivel de los artistas. Es as\u00ed que trabajar\u00e1n con nosotros GID Sonidos, con pantallas gigantes, equipos y luces de \u00faltima tecnolog\u00eda. Est\u00e1 todo listo para que los turistas y salte\u00f1os disfrutemos del festival y de todo lo que les ofrece la localidad.<\/p>\n<p>\u00bfQu\u00e9 m\u00e1s ofrece Molinos al visitante?<\/p>\n<p>Molinos se destaca y deslumbra por su cultura, por sus tradiciones. El festival tambi\u00e9n tendr\u00e1 un segmento de actividades de destreza criolla el s\u00e1bado. La localidad hoy cuenta con todas las comodidades, como hostales, casas de comida t\u00edpica, un complejo polideportivo con gimnasio para ser disfrutado al m\u00e1ximo. Los paisajes y las bellezas naturales de nuestra tierra son un p\u00e1rrafo aparte. Quienes nos visitan suelen recorrer nuestra hermosa serran\u00eda, pasear cerca del r\u00edo y caminar nuestras calles, que los remonta a otros tiempos, ya que se destaca por un cuidado estilo colonial. El centro de interpretaci\u00f3n que funciona en la casa de Indalecio G\u00f3mez, la iglesia, la casa del \u00faltimo gobernador realista de Salta y las bodegas son solo algunos de los atractivos que tenemos para los turistas. Los trabajos artesanales, especialmente los productos textiles y de tejidos realizados con t\u00e9cnicas ancestrales, ocupan un lugar importante en nuestra cultura y est\u00e1n a disposici\u00f3n de los visitantes. Sin dudas, Molinos es una excelente opci\u00f3n para este verano y se encuentra a solo 200 km de la ciudad de Salta, a 45 km de Cachi y a poco m\u00e1s de 100 km de Cafayate. Molinos es un pueblo que invita a divertirse, pero tambi\u00e9n a descansar.<\/p>\n<p>Por primera vez recibir\u00e1n al primer turista para abrir oficialmente la temporada&#8230;<\/p>\n<p>S\u00ed. Estamos muy entusiasmados y ansiosos de recibir al primer turista y as\u00ed abrir oficialmente la temporada de verano. En este camino de consolidarnos como destino en el itinerario de quienes visitan Salta, incorporamos este a\u00f1o a la recepci\u00f3n del primer turista. La idea es agasajarlo y que se lleve o se lleven de la localidad el mejor de los recuerdos, especialmente de la calidez de la gente. Tenemos preparadas varias sorpresas y presentes. Molinos ha venido creciendo a\u00f1o a a\u00f1o y posicion\u00e1ndose en materia tur\u00edstica a trav\u00e9s de festivales, ferias de peque\u00f1os productores y artesanos, eventos deportivos, entre otros. Adem\u00e1s fuimos incorporando infraestructura para que los visitantes gocen de la tradici\u00f3n, pero tambi\u00e9n cuenten con todas las comodidades, como por ejemplo conectividad a internet, alojamiento, gastronom\u00eda, etc.<\/p>\n<p>\u00bfQu\u00e9 lugar ocupa el turismo en el plan de pol\u00edticas p\u00fablicas del municipio?<\/p>\n<p>Y ocupa un lugar cada vez mayor. Pero apuntamos a que el crecimiento del turismo vaya en paralelo con la mejora en la calidad de vida de nuestros vecinos. Si somos un pueblo que cuenta con comodidades, en el que la gente puede desarrollarse entonces el turismo definitivamente se fortalece.<\/p>\n<p>Hay que estar bien y mostrarse bien para que la gente tenga el deseo de conocernos. Es un pueblo pintoresco, con grandes atractivos naturales y culturales, que conserva sus tradiciones pero que tambi\u00e9n quiere crecer y disfrutar de los avances de la tecnolog\u00eda y de lo que ofrece el mundo actual.<\/p>\n<p>El desaf\u00edo es transitar esos dos caminos de manera simult\u00e1nea, sin que uno deje afuera al otro. Y lo estamos logrando. Hoy el turista que visita Salta sabe de Molinos y lo ha sumado a su itinerario. Este es un avance decisivo en el camino que hemos emprendido de dar a conocer la localidad a la Argentina y el Mundo.<\/p>\n<h6>Fuente: El Tribuno<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>El intendente de Molinos, Walter Chocobar, cont\u00f3 a El Tribuno acerca de los artistas que integran la cartelera del megafestival folcl\u00f3rico a realizarse en ese lugar del Valle Calchaqu\u00ed el pr\u00f3ximo 24 y 25 del corriente<\/p>\n","protected":false},"author":2,"featured_media":98439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[9],"class_list":["post-98438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiestas","tag-salta"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=98438"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/98439"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=98438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=98438"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=98438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}