{"id":98540,"date":"2020-01-22T08:04:50","date_gmt":"2020-01-22T11:04:50","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=98540"},"modified":"2020-01-22T08:04:50","modified_gmt":"2020-01-22T11:04:50","slug":"comenzo-la-fiesta-nacional-de-la-playa-de-rio-en-concepcion-del-uruguay","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/comenzo-la-fiesta-nacional-de-la-playa-de-rio-en-concepcion-del-uruguay\/","title":{"rendered":"Comenz\u00f3 la Fiesta Nacional de la Playa de R\u00edo en Concepci\u00f3n del Uruguay"},"content":{"rendered":"<p>Este martes con la actuaci\u00f3n de bandas locales dio inicio la XXXII edici\u00f3n de la Fiesta Nacional de la Playa de R\u00edo en el predio Multieventos de Concepci\u00f3n del Uruguay. Seguir\u00e1 hasta el domingo.<\/p>\n<p>Con bandas locales, comenz\u00f3 la Fiesta Nacional de la Playa de R\u00edo en Concepci\u00f3n del Uruguay. La actividad sobre el escenario continuar\u00e1 este mi\u00e9rcoles 22 ya con los shows de los artistas principales, acompa\u00f1ados en todos los casos de una larga lista de bandas locales. Y se podr\u00e1 ver por Elonce TV.<\/p>\n<p>Los artista nacionales ser\u00e1n Miss Bolivia (22\/01), La Beriso (23\/01), Los Palmeras (24\/01), Karina \u00abLa Princesita\u00bb (25\/01), El Chaque\u00f1o Palavecino y No Te Va Gustar (26\/01).<\/p>\n<p>Ya comenzaron tambi\u00e9n con el armado de los foodtrucks que integrar\u00e1n un paseo gastron\u00f3mico y el tradicional paseo de artesanos a partir de este mi\u00e9rcoles.<\/p>\n<p>Se dispondr\u00e1 de estacionamiento con seguridad a cargo de Bomberos Voluntarios y se realizar\u00e1 el cerramiento perimetral acorde a la magnitud del evento.<\/p>\n<p>Las entradas anticipadas y las plateas contin\u00faan a la venta en la Isla del Puerto, de 12:00 a 21:00 (P\u00f3rtico de Ingreso) hasta el s\u00e1bado 25 inclusive. Por internet se pueden comprar las 24 horas en la p\u00e1gina de\u00a0www.1000tickets.com.ar, al igual que por tel\u00e9fono al 0810-777-8484. Tambi\u00e9n est\u00e1 disponible la compra de plateas. Las anticipadas estar\u00e1n vigentes hasta el d\u00eda previo a cada uno de los shows.<\/p>\n<h6>Fuente: El Once<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>Este martes con la actuaci\u00f3n de bandas locales dio inicio la XXXII edici\u00f3n de la Fiesta Nacional de la Playa de R\u00edo en el predio Multieventos de Concepci\u00f3n del Uruguay. Seguir\u00e1 hasta el domingo.<\/p>\n","protected":false},"author":2,"featured_media":98541,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[47],"tags":[17],"class_list":["post-98540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fiestas","tag-entre-rios"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=98540"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/98541"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=98540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=98540"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=98540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}