{"id":98641,"date":"2020-01-24T07:46:20","date_gmt":"2020-01-24T10:46:20","guid":{"rendered":"http:\/\/argentinamunicipal.com.ar\/argentina\/?p=98641"},"modified":"2020-01-24T07:46:20","modified_gmt":"2020-01-24T10:46:20","slug":"el-suoem-cordoba-lanzo-un-plan-de-asambleas-en-reclamo-por-contratos-caidos","status":"publish","type":"post","link":"http:\/\/argentinamunicipal.com.ar\/argentina\/el-suoem-cordoba-lanzo-un-plan-de-asambleas-en-reclamo-por-contratos-caidos\/","title":{"rendered":"El Suoem C\u00f3rdoba lanz\u00f3 un plan de asambleas en reclamo por contratos ca\u00eddos"},"content":{"rendered":"<p>La actividad de la Municipalidad estar\u00e1 resentida durante varias horas hoy cuando el Sindicato Uni\u00f3n Obreros y Empleados Municipales (Suoem) realice una nueva asamblea de delegados en protesta por la ca\u00edda de contratos en este verano.<\/p>\n<p>As\u00ed lo anunci\u00f3 ayer el gremio, atento a que unos 30 contratos regidos por los art\u00edculos 8 y 9 del Estatuto del Personal Municipal (Ordenanza 7.244) no fueron renovados en la nueva gesti\u00f3n del intendente Mart\u00edn Llaryora.<\/p>\n<p>El gremio replic\u00f3 en sus redes sociales que la medida de fuerza se har\u00e1 una vez m\u00e1s en el Palacio 6 de Julio, un cl\u00e1sico del sindicato, y ser\u00e1 \u201cen defensa de la fuente de trabajo\u201d.<\/p>\n<p>Desde el municipio, prefieren sostener el bajo perfil y aseguran que se est\u00e1 negociando la necesidad de cada uno de esos puestos para las \u00e1reas afectadas. Sin embargo, a pesar de la consulta de\u00a0La Voz,\u00a0no hubo una manifestaci\u00f3n p\u00fablica al respecto.<\/p>\n<p>Contrariamente, desde el gremio afirmaron que \u201chace d\u00edas no hay di\u00e1logo con Ver\u00f3nica Bruera\u201d, la secretaria General de la Municipalidad que lleva adelante negociaciones por salarios con el Suoem.<\/p>\n<p>Precisamente, las \u00faltimas reuniones con la funcionaria comunicadas fueron la primera semana de enero, cuando estaba en disputa la actualizaci\u00f3n de los salarios municipales por inflaci\u00f3n.<\/p>\n<p>En ese entonces, ya se discut\u00edan los contratos ca\u00eddos \u201cuno a uno\u201d, seg\u00fan la versi\u00f3n del sindicato y la resoluci\u00f3n del conflicto principal, con un aumento del 4,29 por ciento en los salarios, trajo una paz temporaria.<\/p>\n<p>No obstante, el gremio decidi\u00f3 avanzar y llevar la pelea a otro plano y, en consecuencia, a las 10 habr\u00e1 una concentraci\u00f3n de trabajadores municipales de \u00e1reas afectadas en la explanada del edificio principal de la Municipalidad. Esta situaci\u00f3n, como en cada asamblea, dificultar\u00e1 la atenci\u00f3n al p\u00fablico.<\/p>\n<p>Como antecedente, antes de A\u00f1o Nuevo, el gremio decidi\u00f3 marchar hasta el edificio de calle Marcelo T. de Alvear 120 tras una asamblea, y la Polic\u00eda cerr\u00f3 las puertas de ingreso durante la hora en que se desarroll\u00f3 la protesta.<\/p>\n<p>La de hoy ser\u00e1 la segunda manifestaci\u00f3n contra Llaryora. En la asamblea estar\u00e1n la conducci\u00f3n sindical, delegados gremiales y activistas.<\/p>\n<p><strong>Temprano<\/strong><\/p>\n<p>El sindicato inform\u00f3 que ya se convocaron varias asambleas a primera hora de la ma\u00f1ana de hoy en las \u00e1reas de Medicina Laboral, Promoci\u00f3n Familiar, Hogares de D\u00eda y los CPC Pueyrred\u00f3n y San Vicente, algunas de las dependencias afectadas por el recorte de contratos. Tambi\u00e9n, seg\u00fan la fuente sindical, el recorte afect\u00f3 el \u00e1rea de Educaci\u00f3n, donde \u201cno renovaron contrato de algunos auxiliares escolares\u201d.<\/p>\n<p>\u201cSe trata de compa\u00f1eros que tienen entre tres y cinco a\u00f1os de antig\u00fcedad\u201d, dijo el vocero del Suoem, Dami\u00e1n Bizzi. En realidad, el n\u00famero de contratos ca\u00eddos es superior al que denuncia el Suoem, s\u00f3lo que incluye tambi\u00e9n a numerosas incorporaciones producidas en las \u00faltimas semanas de la gesti\u00f3n del exintendente Ram\u00f3n Mestre. En esos casos, el gremio no objetar\u00eda las desvinculaciones.<\/p>\n<p>El Ejecutivo tambi\u00e9n est\u00e1 revisando \u2013y registrando en muchos casos\u2013 la cantidad de monotributistas que se desempe\u00f1an en el municipio.<\/p>\n<p><strong>Clima<\/strong><\/p>\n<p>La tensi\u00f3n en el municipio fue subiendo en estos primeros d\u00edas de gesti\u00f3n. Desde el ingreso de Llaryora al edificio entre abrazos, saludos y\u00a0selfies\u00a0con algunos empleados tras su asunci\u00f3n como intendente en diciembre pasado, la fricci\u00f3n entre las autoridades y el gremio vivi\u00f3 varios cap\u00edtulos que cambiaron el clima.<\/p>\n<p>El primero fue cuando se aprob\u00f3 la ordenanza que declara la emergencia econ\u00f3mica, financiera, administrativa y social del municipio. Esta normativa que el intendente envi\u00f3 al Concejo Deliberante reflej\u00f3 varios cambios no acordados con el gremio en cuanto a la pol\u00edtica de personal.<\/p>\n<p>Luego, la pelea sigui\u00f3 por el frente salarial cuando se plantearon dudas sobre la aplicaci\u00f3n de la \u201ccl\u00e1usula gatillo\u201d a los salarios de diciembre. El acuerdo salarial se extiende hasta este mes, y en febrero la gesti\u00f3n Llaryora debe discutir la nueva paritaria.<\/p>\n<h6>Fuente: La Voz<\/h6>\n","protected":false},"excerpt":{"rendered":"<p>La actividad de la Municipalidad estar\u00e1 resentida durante varias horas hoy cuando el Sindicato Uni\u00f3n Obreros y Empleados Municipales (Suoem) realice una nueva asamblea de delegados en protesta por la ca\u00edda de contratos en este verano.<\/p>\n","protected":false},"author":2,"featured_media":98642,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[3],"class_list":["post-98641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-informe-sindical","tag-cordoba"],"_links":{"self":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/comments?post=98641"}],"version-history":[{"count":0,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/posts\/98641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media\/98642"}],"wp:attachment":[{"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/media?parent=98641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/categories?post=98641"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/argentinamunicipal.com.ar\/argentina\/wp-json\/wp\/v2\/tags?post=98641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}